{"id":1399,"date":"2019-09-24T15:27:51","date_gmt":"2019-09-24T13:27:51","guid":{"rendered":"https:\/\/ipaidthat.io\/mag\/?p=1399"},"modified":"2019-09-24T15:27:51","modified_gmt":"2019-09-24T13:27:51","slug":"nextfinance-parle-dipaidthat","status":"publish","type":"post","link":"https:\/\/app.ipaidthat.io\/mag\/nos-actualites\/nextfinance-parle-dipaidthat\/","title":{"rendered":"NextFinance parle d&rsquo;iPaidThat"},"content":{"rendered":"\n<figure class=\"wp-block-image\"><a href=\"https:\/\/www.next-finance.net\/La-start-up-iPaidThat-boucle-une\" target=\"_blank\" rel=\"noreferrer noopener\"><img decoding=\"async\" src=\"https:\/\/ipaidthat.io\/mag\/wp-content\/uploads\/2019\/09\/NextFinance-x-iPaidThat.png\" alt=\"\" class=\"wp-image-1400\"\/><\/a><\/figure>\n\n\n\n<h2 class=\"wp-block-heading\">D\u00e9couvrez l&rsquo;article<\/h2>\n\n\n\n<p>NextFinance parle d&rsquo;iPaidThat. Vous pouvez retrouver l&rsquo;article sur <a aria-label=\"ce lien. (s\u2019ouvre dans un nouvel onglet)\" href=\"https:\/\/www.next-finance.net\/La-start-up-iPaidThat-boucle-une\" target=\"_blank\" rel=\"noreferrer noopener\">ce lien.<\/a> <\/p>\n","protected":false},"excerpt":{"rendered":"<p>D\u00e9couvrez l&rsquo;article NextFinance parle d&rsquo;iPaidThat. Vous pouvez retrouver l&rsquo;article sur ce lien.<\/p>\n","protected":false},"author":4,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[3],"tags":[],"class_list":["post-1399","post","type-post","status-publish","format-standard","hentry","category-nos-actualites"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v26.6 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>NextFinance parle d&#039;iPaidThat<\/title>\n<meta name=\"description\" content=\"NextFinance parle de notre lev\u00e9e de fonds de 1.5 million d\u2019euros. Vous pouvez consulter l&#039;article dans le lien sur notre page.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/app.ipaidthat.io\/mag\/nos-actualites\/nextfinance-parle-dipaidthat\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"NextFinance parle d&#039;iPaidThat\" \/>\n<meta property=\"og:description\" content=\"NextFinance parle de notre lev\u00e9e de fonds de 1.5 million d\u2019euros. Vous pouvez consulter l&#039;article dans le lien sur notre page.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/app.ipaidthat.io\/mag\/nos-actualites\/nextfinance-parle-dipaidthat\/\" \/>\n<meta property=\"og:site_name\" content=\"iPaidThat Mag\" \/>\n<meta property=\"article:published_time\" content=\"2019-09-24T13:27:51+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/ipaidthat.io\/mag\/wp-content\/uploads\/2019\/09\/NextFinance-x-iPaidThat.png\" \/>\n<meta name=\"author\" content=\"S\u00e9bastien Claeys\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"S\u00e9bastien Claeys\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/app.ipaidthat.io\/mag\/nos-actualites\/nextfinance-parle-dipaidthat\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/app.ipaidthat.io\/mag\/nos-actualites\/nextfinance-parle-dipaidthat\/\"},\"author\":{\"name\":\"S\u00e9bastien Claeys\",\"@id\":\"https:\/\/app.ipaidthat.io\/mag\/#\/schema\/person\/021144662586a12df79c88913050baaa\"},\"headline\":\"NextFinance parle d&rsquo;iPaidThat\",\"datePublished\":\"2019-09-24T13:27:51+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/app.ipaidthat.io\/mag\/nos-actualites\/nextfinance-parle-dipaidthat\/\"},\"wordCount\":20,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/app.ipaidthat.io\/mag\/#organization\"},\"image\":{\"@id\":\"https:\/\/app.ipaidthat.io\/mag\/nos-actualites\/nextfinance-parle-dipaidthat\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/ipaidthat.io\/mag\/wp-content\/uploads\/2019\/09\/NextFinance-x-iPaidThat.png\",\"articleSection\":[\"Nos Actualit\u00e9s\"],\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/app.ipaidthat.io\/mag\/nos-actualites\/nextfinance-parle-dipaidthat\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/app.ipaidthat.io\/mag\/nos-actualites\/nextfinance-parle-dipaidthat\/\",\"url\":\"https:\/\/app.ipaidthat.io\/mag\/nos-actualites\/nextfinance-parle-dipaidthat\/\",\"name\":\"NextFinance parle d'iPaidThat\",\"isPartOf\":{\"@id\":\"https:\/\/app.ipaidthat.io\/mag\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/app.ipaidthat.io\/mag\/nos-actualites\/nextfinance-parle-dipaidthat\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/app.ipaidthat.io\/mag\/nos-actualites\/nextfinance-parle-dipaidthat\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/ipaidthat.io\/mag\/wp-content\/uploads\/2019\/09\/NextFinance-x-iPaidThat.png\",\"datePublished\":\"2019-09-24T13:27:51+00:00\",\"description\":\"NextFinance parle de notre lev\u00e9e de fonds de 1.5 million d\u2019euros. Vous pouvez consulter l'article dans le lien sur notre page.\",\"breadcrumb\":{\"@id\":\"https:\/\/app.ipaidthat.io\/mag\/nos-actualites\/nextfinance-parle-dipaidthat\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/app.ipaidthat.io\/mag\/nos-actualites\/nextfinance-parle-dipaidthat\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/app.ipaidthat.io\/mag\/nos-actualites\/nextfinance-parle-dipaidthat\/#primaryimage\",\"url\":\"https:\/\/ipaidthat.io\/mag\/wp-content\/uploads\/2019\/09\/NextFinance-x-iPaidThat.png\",\"contentUrl\":\"https:\/\/ipaidthat.io\/mag\/wp-content\/uploads\/2019\/09\/NextFinance-x-iPaidThat.png\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/app.ipaidthat.io\/mag\/nos-actualites\/nextfinance-parle-dipaidthat\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Le Mag\",\"item\":\"https:\/\/app.ipaidthat.io\/mag\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Nos Actualit\u00e9s\",\"item\":\"https:\/\/app.ipaidthat.io\/mag\/category\/nos-actualites\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"NextFinance parle d&rsquo;iPaidThat\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/app.ipaidthat.io\/mag\/#website\",\"url\":\"https:\/\/app.ipaidthat.io\/mag\/\",\"name\":\"IPaidThat Mag\",\"description\":\"Une gestion simple, automatis\u00e9e et collaborative\",\"publisher\":{\"@id\":\"https:\/\/app.ipaidthat.io\/mag\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/app.ipaidthat.io\/mag\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/app.ipaidthat.io\/mag\/#organization\",\"name\":\"IPaidThat Mag\",\"url\":\"https:\/\/app.ipaidthat.io\/mag\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/app.ipaidthat.io\/mag\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/app.ipaidthat.io\/mag\/wp-content\/uploads\/2025\/11\/logo-le-mag-blog-ipaidthat.png\",\"contentUrl\":\"https:\/\/app.ipaidthat.io\/mag\/wp-content\/uploads\/2025\/11\/logo-le-mag-blog-ipaidthat.png\",\"width\":1817,\"height\":524,\"caption\":\"IPaidThat Mag\"},\"image\":{\"@id\":\"https:\/\/app.ipaidthat.io\/mag\/#\/schema\/logo\/image\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\/\/app.ipaidthat.io\/mag\/#\/schema\/person\/021144662586a12df79c88913050baaa\",\"name\":\"S\u00e9bastien Claeys\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/app.ipaidthat.io\/mag\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/app.ipaidthat.io\/mag\/wp-content\/uploads\/2023\/02\/sebastien-clayes-ipaidthat-96x96.png\",\"contentUrl\":\"https:\/\/app.ipaidthat.io\/mag\/wp-content\/uploads\/2023\/02\/sebastien-clayes-ipaidthat-96x96.png\",\"caption\":\"S\u00e9bastien Claeys\"},\"url\":\"https:\/\/app.ipaidthat.io\/mag\/author\/sebastienipaidthat-io\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"NextFinance parle d'iPaidThat","description":"NextFinance parle de notre lev\u00e9e de fonds de 1.5 million d\u2019euros. Vous pouvez consulter l'article dans le lien sur notre page.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/app.ipaidthat.io\/mag\/nos-actualites\/nextfinance-parle-dipaidthat\/","og_locale":"fr_FR","og_type":"article","og_title":"NextFinance parle d'iPaidThat","og_description":"NextFinance parle de notre lev\u00e9e de fonds de 1.5 million d\u2019euros. Vous pouvez consulter l'article dans le lien sur notre page.","og_url":"https:\/\/app.ipaidthat.io\/mag\/nos-actualites\/nextfinance-parle-dipaidthat\/","og_site_name":"iPaidThat Mag","article_published_time":"2019-09-24T13:27:51+00:00","og_image":[{"url":"https:\/\/ipaidthat.io\/mag\/wp-content\/uploads\/2019\/09\/NextFinance-x-iPaidThat.png","type":"","width":"","height":""}],"author":"S\u00e9bastien Claeys","twitter_card":"summary_large_image","twitter_misc":{"\u00c9crit par":"S\u00e9bastien Claeys","Dur\u00e9e de lecture estim\u00e9e":"1 minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/app.ipaidthat.io\/mag\/nos-actualites\/nextfinance-parle-dipaidthat\/#article","isPartOf":{"@id":"https:\/\/app.ipaidthat.io\/mag\/nos-actualites\/nextfinance-parle-dipaidthat\/"},"author":{"name":"S\u00e9bastien Claeys","@id":"https:\/\/app.ipaidthat.io\/mag\/#\/schema\/person\/021144662586a12df79c88913050baaa"},"headline":"NextFinance parle d&rsquo;iPaidThat","datePublished":"2019-09-24T13:27:51+00:00","mainEntityOfPage":{"@id":"https:\/\/app.ipaidthat.io\/mag\/nos-actualites\/nextfinance-parle-dipaidthat\/"},"wordCount":20,"commentCount":0,"publisher":{"@id":"https:\/\/app.ipaidthat.io\/mag\/#organization"},"image":{"@id":"https:\/\/app.ipaidthat.io\/mag\/nos-actualites\/nextfinance-parle-dipaidthat\/#primaryimage"},"thumbnailUrl":"https:\/\/ipaidthat.io\/mag\/wp-content\/uploads\/2019\/09\/NextFinance-x-iPaidThat.png","articleSection":["Nos Actualit\u00e9s"],"inLanguage":"fr-FR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/app.ipaidthat.io\/mag\/nos-actualites\/nextfinance-parle-dipaidthat\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/app.ipaidthat.io\/mag\/nos-actualites\/nextfinance-parle-dipaidthat\/","url":"https:\/\/app.ipaidthat.io\/mag\/nos-actualites\/nextfinance-parle-dipaidthat\/","name":"NextFinance parle d'iPaidThat","isPartOf":{"@id":"https:\/\/app.ipaidthat.io\/mag\/#website"},"primaryImageOfPage":{"@id":"https:\/\/app.ipaidthat.io\/mag\/nos-actualites\/nextfinance-parle-dipaidthat\/#primaryimage"},"image":{"@id":"https:\/\/app.ipaidthat.io\/mag\/nos-actualites\/nextfinance-parle-dipaidthat\/#primaryimage"},"thumbnailUrl":"https:\/\/ipaidthat.io\/mag\/wp-content\/uploads\/2019\/09\/NextFinance-x-iPaidThat.png","datePublished":"2019-09-24T13:27:51+00:00","description":"NextFinance parle de notre lev\u00e9e de fonds de 1.5 million d\u2019euros. Vous pouvez consulter l'article dans le lien sur notre page.","breadcrumb":{"@id":"https:\/\/app.ipaidthat.io\/mag\/nos-actualites\/nextfinance-parle-dipaidthat\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/app.ipaidthat.io\/mag\/nos-actualites\/nextfinance-parle-dipaidthat\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/app.ipaidthat.io\/mag\/nos-actualites\/nextfinance-parle-dipaidthat\/#primaryimage","url":"https:\/\/ipaidthat.io\/mag\/wp-content\/uploads\/2019\/09\/NextFinance-x-iPaidThat.png","contentUrl":"https:\/\/ipaidthat.io\/mag\/wp-content\/uploads\/2019\/09\/NextFinance-x-iPaidThat.png"},{"@type":"BreadcrumbList","@id":"https:\/\/app.ipaidthat.io\/mag\/nos-actualites\/nextfinance-parle-dipaidthat\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Le Mag","item":"https:\/\/app.ipaidthat.io\/mag\/"},{"@type":"ListItem","position":2,"name":"Nos Actualit\u00e9s","item":"https:\/\/app.ipaidthat.io\/mag\/category\/nos-actualites\/"},{"@type":"ListItem","position":3,"name":"NextFinance parle d&rsquo;iPaidThat"}]},{"@type":"WebSite","@id":"https:\/\/app.ipaidthat.io\/mag\/#website","url":"https:\/\/app.ipaidthat.io\/mag\/","name":"IPaidThat Mag","description":"Une gestion simple, automatis\u00e9e et collaborative","publisher":{"@id":"https:\/\/app.ipaidthat.io\/mag\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/app.ipaidthat.io\/mag\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/app.ipaidthat.io\/mag\/#organization","name":"IPaidThat Mag","url":"https:\/\/app.ipaidthat.io\/mag\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/app.ipaidthat.io\/mag\/#\/schema\/logo\/image\/","url":"https:\/\/app.ipaidthat.io\/mag\/wp-content\/uploads\/2025\/11\/logo-le-mag-blog-ipaidthat.png","contentUrl":"https:\/\/app.ipaidthat.io\/mag\/wp-content\/uploads\/2025\/11\/logo-le-mag-blog-ipaidthat.png","width":1817,"height":524,"caption":"IPaidThat Mag"},"image":{"@id":"https:\/\/app.ipaidthat.io\/mag\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/app.ipaidthat.io\/mag\/#\/schema\/person\/021144662586a12df79c88913050baaa","name":"S\u00e9bastien Claeys","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/app.ipaidthat.io\/mag\/#\/schema\/person\/image\/","url":"https:\/\/app.ipaidthat.io\/mag\/wp-content\/uploads\/2023\/02\/sebastien-clayes-ipaidthat-96x96.png","contentUrl":"https:\/\/app.ipaidthat.io\/mag\/wp-content\/uploads\/2023\/02\/sebastien-clayes-ipaidthat-96x96.png","caption":"S\u00e9bastien Claeys"},"url":"https:\/\/app.ipaidthat.io\/mag\/author\/sebastienipaidthat-io\/"}]}},"_links":{"self":[{"href":"https:\/\/app.ipaidthat.io\/mag\/wp-json\/wp\/v2\/posts\/1399","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/app.ipaidthat.io\/mag\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/app.ipaidthat.io\/mag\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/app.ipaidthat.io\/mag\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/app.ipaidthat.io\/mag\/wp-json\/wp\/v2\/comments?post=1399"}],"version-history":[{"count":0,"href":"https:\/\/app.ipaidthat.io\/mag\/wp-json\/wp\/v2\/posts\/1399\/revisions"}],"wp:attachment":[{"href":"https:\/\/app.ipaidthat.io\/mag\/wp-json\/wp\/v2\/media?parent=1399"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/app.ipaidthat.io\/mag\/wp-json\/wp\/v2\/categories?post=1399"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/app.ipaidthat.io\/mag\/wp-json\/wp\/v2\/tags?post=1399"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}