{"id":12373,"date":"2022-10-25T10:05:00","date_gmt":"2022-10-25T08:05:00","guid":{"rendered":"https:\/\/ipaidthat.io\/mag\/?p=12373"},"modified":"2025-12-29T11:51:51","modified_gmt":"2025-12-29T10:51:51","slug":"lamortissement-comptable-comprendre-calculer-et-comptabiliser","status":"publish","type":"post","link":"https:\/\/app.ipaidthat.io\/mag\/comptabilite\/lamortissement-comptable-comprendre-calculer-et-comptabiliser\/","title":{"rendered":"L\u2019amortissement comptable : comprendre, calculer et comptabiliser"},"content":{"rendered":"\n<p>Les investissements, qui ont pour but de d\u00e9velopper votre activit\u00e9, de produire des avantages \u00e9conomiques \u00e0 moyen et long termes, s\u2019enregistrent \u00e0 l\u2019actif de votre bilan, au niveau des <strong>immobilisations<\/strong>. Tous les ans, au moment de la cl\u00f4ture de l\u2019exercice, vous devez saisir dans votre comptabilit\u00e9 leur perte de valeur sous forme d\u2019<strong>amortissement comptable<\/strong>.<\/p>\n\n\n\n<p>Quelle est la d\u00e9marche \u00e0 suivre pour y parvenir&nbsp;? Nous d\u00e9roulons avec vous tout le processus de comptabilisation et de calcul des amortissements comptable&nbsp;et fiscal&nbsp;: les immobilisations amortissables, la base de calcul, les dur\u00e9es et les m\u00e9thodes existantes.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">\u00c0 quoi sert l\u2019amortissement comptable&nbsp;?<\/h2>\n\n\n\n<p>L\u2019amortissement comptable vise \u00e0 <strong>constater la perte de valeur d\u2019un actif inscrit au bilan<\/strong>, qui r\u00e9sulte d\u2019une usure physique ou de son obsolescence.&nbsp;<\/p>\n\n\n\n<p>Quand vous achetez des fournitures de bureau, cette d\u00e9pense s\u2019enregistre directement en compte de charges et impacte votre r\u00e9sultat de l\u2019ann\u00e9e. En g\u00e9n\u00e9ral, ces achats repr\u00e9sentent un faible montant et sont \u00e0 consommer pour des besoins imm\u00e9diats.<\/p>\n\n\n\n<p>En revanche, si vous investissez dans un nouvel ordinateur, celui-ci doit produire des <strong>avantages \u00e9conomiques<\/strong> pour une dur\u00e9e qui d\u00e9passe celle de l\u2019exercice. Vous comptabilisez donc cette d\u00e9pense en immobilisations dans un compte de classe&nbsp;2. Cependant, ce mat\u00e9riel vieillit et sa performance au fil du temps diminue. Ainsi, chaque ann\u00e9e, \u00e0 la cl\u00f4ture, vous saisissez une \u00e9criture comptable d\u2019amortissement qui correspond \u00e0 cette perte de valeur.&nbsp;<\/p>\n\n\n\n<p>L\u2019achat affecte alors le r\u00e9sultat comptable sur plusieurs ann\u00e9es tout comme les b\u00e9n\u00e9fices qu\u2019il apporte \u00e0 l\u2019activit\u00e9 de l\u2019entreprise.&nbsp;<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">Immobilisations amortissables<\/h2>\n\n\n\n<p>L\u2019administration fiscale soumet la d\u00e9duction des amortissements \u00e0 certaines conditions&nbsp;:&nbsp;<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>les actifs immobilis\u00e9s doivent se d\u00e9pr\u00e9cier avec l\u2019usage et le temps\u00a0;<\/li>\n\n\n\n<li>les amortissements correspondent \u00e0 la d\u00e9pr\u00e9ciation effective du bien\u00a0;<\/li>\n\n\n\n<li>ils sont enregistr\u00e9s en comptabilit\u00e9.<\/li>\n<\/ul>\n\n\n\n<p>Une entreprise peut donc amortir une immobilisation si elle <strong>d\u00e9finit son utilisation dans un temps donn\u00e9<\/strong>.&nbsp;<\/p>\n\n\n\n<p>Les Finances publiques proposent une \u00e9tude au cas par cas des <a href=\"https:\/\/bofip.impots.gouv.fr\/bofip\/4590-PGP.html\/identifiant=BOI-BIC-AMT-10-20-20220608#Elements_incorporels_11\" target=\"_blank\" rel=\"noreferrer noopener nofollow\">\u00e9l\u00e9ments amortissables<\/a> et distinguent les actifs corporels et incorporels.<\/p>\n\n\n\n<figure class=\"wp-block-table is-style-regular has-small-font-size\"><table class=\"has-white-color has-text-color has-background\" style=\"background-color:#ff3c3c\"><tbody><tr><td><strong>\u00c9l\u00e9ments incorporels<\/strong><\/td><\/tr><tr><td>Actifs amortissables<\/td><td>Actifs non amortissables<\/td><\/tr><tr><td>Brevets d\u2019invention&nbsp;<br>Frais de recherche et d\u00e9veloppement<br>Frais d\u2019acquisition de titres de participation<br>Frais d\u2019\u00e9tablissement<\/td><td>En principe, la plupart des immobilisations incorporelles ne sont pas amortissables. <br>Fonds commercial (sauf exception) <br>Droits au bail&nbsp;<br>Droits d\u2019exclusivit\u00e9 g\u00e9ographique, etc.<\/td><\/tr><\/tbody><\/table><\/figure>\n\n\n\n<p><\/p>\n\n\n\n<figure class=\"wp-block-table is-style-regular has-small-font-size\"><table class=\"has-background\" style=\"background-color:#ffe6e6\"><tbody><tr><td><strong>\u00c9l\u00e9ments corporels<\/strong><\/td><\/tr><tr><td>Actifs amortissables<\/td><td>Actifs non amortissables<\/td><\/tr><tr><td>En r\u00e8gle g\u00e9n\u00e9rale, les immobilisations corporelles sont amortissables. <br>Constructions <br>Agencements et am\u00e9nagements<br>Installations techniques<br>Mat\u00e9riel de transport<br>Mat\u00e9riel de bureau et informatique<br>Emballages r\u00e9cup\u00e9rables<br>Logiciels<\/td><td>Terrain<br>\u0152uvres d\u2019art<\/td><\/tr><\/tbody><\/table><\/figure>\n\n\n\n<p><em>Bon \u00e0 savoir&nbsp;: <\/em>les biens dont la <strong>valeur n\u2019exc\u00e8de pas 500&nbsp;\u20ac HT<\/strong> peuvent \u00eatre comptabilis\u00e9s directement dans les charges de l\u2019exercice en cours. Les immobilisations financi\u00e8res ne sont pas amortissables.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">Base de calcul de l\u2019amortissement comptable<\/h2>\n\n\n\n<p>La base de calcul de l\u2019amortissement comptable correspond \u00e0 la <strong>valeur brute de l\u2019actif immobilis\u00e9<\/strong>. \u00c0 ce montant, on soustrait la valeur r\u00e9siduelle si elle est significative et mesurable.<\/p>\n\n\n\n<p>Les immobilisations sont enregistr\u00e9es \u00e0 leur date d\u2019entr\u00e9e dans l\u2019entreprise&nbsp;:&nbsp;<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>au co\u00fbt d\u2019acquisition pour les biens acquis \u00e0 titre on\u00e9reux (prix d\u2019achat apr\u00e8s d\u00e9duction des remises, rabais et escomptes de r\u00e8glement, et frais annexes de transport, d\u2019installation, etc.)\u00a0;<\/li>\n\n\n\n<li>\u00e0 la valeur v\u00e9nale de l\u2019actif pour ceux re\u00e7us \u00e0 titre gratuit\u00a0;<\/li>\n\n\n\n<li>\u00e0 leur co\u00fbt de production pour les biens produits par l\u2019entreprise.<\/li>\n<\/ul>\n\n\n\n<p>La base de calcul de l\u2019amortissement est parfois <strong>plafonn\u00e9e<\/strong>. C\u2019est le cas des <strong>v\u00e9hicules de tourisme,<\/strong> dont la valeur amortissable n\u2019exc\u00e8de pas 18&nbsp;300&nbsp;\u20ac. L\u2019article&nbsp;39 du Code g\u00e9n\u00e9ral des imp\u00f4ts pr\u00e9voit toutefois une modification de ce seuil de d\u00e9ductibilit\u00e9 en fonction des \u00e9missions de dioxyde de carbone. Ainsi, les v\u00e9hicules polluants voient leur plafond s\u2019abaisser \u00e0 9\u2009900&nbsp;\u20ac alors que les moins polluants peuvent d\u00e9duire jusqu\u2019\u00e0 30&nbsp;000&nbsp;\u20ac.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">Dur\u00e9es d\u2019amortissement des actifs immobilis\u00e9s<\/h2>\n\n\n\n<h3 class=\"wp-block-heading\">La dur\u00e9e d\u2019utilisation de l\u2019actif<\/h3>\n\n\n\n<p>Selon le <a href=\"https:\/\/ipaidthat.io\/mag\/comptabilite\/plan-comptable-general-le-guide-pour-la-tenue-de-votre-comptabilite\/\" target=\"_blank\" rel=\"noreferrer noopener\">Plan comptable g\u00e9n\u00e9ral<\/a> (PCG), l\u2019amortissement comptable se calcule sur la <strong>dur\u00e9e r\u00e9elle d\u2019utilisation <\/strong>du bien. Ainsi, l\u2019emploi fr\u00e9quent d\u2019un actif entra\u00eene une usure plus rapide et une dur\u00e9e d\u2019amortissement r\u00e9duite pour une entreprise, mais pas n\u00e9cessairement pour une autre, qui peut alors choisir une dur\u00e9e plus longue.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\">La dur\u00e9e d\u2019usage de l\u2019actif<\/h3>\n\n\n\n<p>L\u2019administration fiscale s\u2019appuie, quant \u00e0 elle, sur la <strong>dur\u00e9e d\u2019usage<\/strong> de la profession pour calculer les amortissements admis en d\u00e9duction (<a href=\"https:\/\/www.legifrance.gouv.fr\/codes\/article_lc\/LEGIARTI000027518420\/2013-06-07\" target=\"_blank\" rel=\"noreferrer noopener nofollow\">article&nbsp;39 du Code g\u00e9n\u00e9ral des imp\u00f4ts<\/a>).<\/p>\n\n\n\n<figure class=\"wp-block-table is-style-stripes has-small-font-size\"><table class=\"has-black-color has-text-color\"><tbody><tr><td><strong>\u00c9l\u00e9ments incorporels<\/strong><\/td><\/tr><tr><td>Actif<\/td><td>Dur\u00e9e d\u2019amortissement<\/td><\/tr><tr><td>Brevets d\u2019invention&nbsp;<\/td><td>5&nbsp;ans<\/td><\/tr><tr><td>Frais de recherche et d\u00e9veloppement<\/td><td>5&nbsp;ans<\/td><\/tr><tr><td>Frais d\u2019acquisition de titres de participation<\/td><td>5&nbsp;ans<\/td><\/tr><tr><td>Frais d\u2019\u00e9tablissement<\/td><td>5&nbsp;ans<\/td><\/tr><\/tbody><\/table><\/figure>\n\n\n\n<p><\/p>\n\n\n\n<figure class=\"wp-block-table is-style-stripes has-small-font-size\"><table><tbody><tr><td><strong>\u00c9l\u00e9ments corporels<\/strong><\/td><\/tr><tr><td>Actif<\/td><td>Dur\u00e9e d\u2019amortissement<\/td><\/tr><tr><td>Constructions&nbsp;de maisons d\u2019habitations, de b\u00e2timents commerciaux, de b\u00e2timents industriels<\/td><td><br>50 \u00e0 100&nbsp;ans20 \u00e0 50&nbsp;ans20&nbsp;ans<\/td><\/tr><tr><td>Mat\u00e9riel et outillage<\/td><td>6 \u00e0 10&nbsp;ans<\/td><\/tr><tr><td>Mat\u00e9riel de transport automobile<\/td><td>4 \u00e0 5&nbsp;ans<\/td><\/tr><tr><td>Mobilier<\/td><td>10&nbsp;ans<\/td><\/tr><tr><td>Agencements et installations<\/td><td>10 \u00e0 20&nbsp;ans<\/td><\/tr><tr><td>Mat\u00e9riel informatique<\/td><td>3 \u00e0 5&nbsp;ans<\/td><\/tr><\/tbody><\/table><\/figure>\n\n\n\n<p>L\u2019administration fiscale <strong>admet un \u00e9cart de 20&nbsp;%<\/strong> avec les usages de la profession.<\/p>\n\n\n\n<p>Une tol\u00e9rance existe <strong>pour les petites entreprises<\/strong> qui ne d\u00e9passent pas 2 des 3&nbsp;seuils suivants&nbsp;:&nbsp;<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>total bilan fix\u00e9 \u00e0 6\u00a0000\u00a0000\u00a0d\u2019euros\u00a0;<\/li>\n\n\n\n<li>montant net du chiffre d\u2019affaires \u00e0 12\u00a0000\u00a0000\u00a0d\u2019euros\u00a0;<\/li>\n\n\n\n<li>nombre de salari\u00e9s \u00e0 50.<\/li>\n<\/ul>\n\n\n\n<p>Elles peuvent adopter les dur\u00e9es d\u2019usage pour le calcul du taux d\u2019amortissement comptable.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\">L\u2019amortissement exceptionnel<\/h3>\n\n\n\n<p>L\u2019amortissement exceptionnel, dit <strong>acc\u00e9l\u00e9r\u00e9,<\/strong> correspond \u00e0 une d\u00e9duction particuli\u00e8re autoris\u00e9e par l\u2019administration fiscale dans certains cas&nbsp;:<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>mat\u00e9riels destin\u00e9s \u00e0 \u00e9conomiser l\u2019\u00e9nergie\u00a0;<\/li>\n\n\n\n<li>v\u00e9hicules \u00e9lectriques\u00a0;<\/li>\n\n\n\n<li>immeubles affect\u00e9s \u00e0 la recherche scientifique\u00a0;<\/li>\n\n\n\n<li>immeubles destin\u00e9s \u00e0 la lutte contre la pollution, etc.<\/li>\n<\/ul>\n\n\n\n<p>L\u2019entreprise d\u00e9roge \u00e0 l\u2019amortissement classique pour imputer des annuit\u00e9s g\u00e9n\u00e9ralement sup\u00e9rieures.&nbsp;<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">Les m\u00e9thodes de calcul d\u2019amortissement comptable<\/h2>\n\n\n\n<p>Les amortissements comptables commencent \u00e0 compter de la <strong>date de mise en service<\/strong> du bien.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\">L\u2019amortissement comptable lin\u00e9aire<\/h3>\n\n\n\n<h4 class=\"wp-block-heading\">La m\u00e9thode d\u2019amortissement lin\u00e9aire<\/h4>\n\n\n\n<p>Le mode lin\u00e9aire correspond au <strong>r\u00e9gime par d\u00e9faut<\/strong>. Le plan d\u2019amortissement est \u00e9tabli en fonction d\u2019une <strong>annuit\u00e9 constante<\/strong> calcul\u00e9e sur la dur\u00e9e d\u2019utilisation de l\u2019actif. Vous comptabilisez tous les ans le m\u00eame montant.<\/p>\n\n\n\n<p>Certains biens sont amortis obligatoirement en suivant le syst\u00e8me lin\u00e9aire&nbsp;:&nbsp;<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>les actifs acquis ou construits avant l\u2019instauration de l\u2019amortissement d\u00e9gressif (1<sup>er<\/sup>\u00a0janvier\u00a01960)\u00a0;<\/li>\n\n\n\n<li>les immobilisations exclues du dispositif de l\u2019amortissement d\u00e9gressif\u00a0;<\/li>\n\n\n\n<li>les biens acquis d\u2019occasion\u00a0;<\/li>\n\n\n\n<li>les actifs dont la dur\u00e9e d\u2019utilisation est inf\u00e9rieure \u00e0 3\u00a0ans.<\/li>\n<\/ul>\n\n\n\n<p>En cas d\u2019acquisition en cours d\u2019exercice, la dotation aux amortissements de la premi\u00e8re ann\u00e9e est d\u00e9termin\u00e9e au <em>prorata temporis<\/em>&nbsp;:&nbsp;<\/p>\n\n\n\n<p>Nombre de jours depuis la mise en service\/Total de jours dans l\u2019ann\u00e9e<\/p>\n\n\n\n<p>La formule pour d\u00e9terminer le <strong>taux d\u2019amortissement lin\u00e9aire en %<\/strong> est la suivante&nbsp;:&nbsp;<\/p>\n\n\n\n<p>100\/nombre d\u2019ann\u00e9es d\u2019utilisation r\u00e9elle.<\/p>\n\n\n\n<h4 class=\"wp-block-heading\">Exemple d\u2019amortissement lin\u00e9aire<\/h4>\n\n\n\n<p>Prenons un <strong>exemple&nbsp;<\/strong>: le 1<sup>er<\/sup>&nbsp;avril de l\u2019ann\u00e9e N, une entreprise ach\u00e8te un mat\u00e9riel pour un montant de 18&nbsp;000&nbsp;\u20ac \u00e0 amortir pour une dur\u00e9e d\u2019utilisation de 5&nbsp;ans. La valeur r\u00e9siduelle estim\u00e9e s\u2019\u00e9l\u00e8ve \u00e0 3\u2009000&nbsp;\u20ac.<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Le taux d\u2019amortissement lin\u00e9aire est de 100\/5 = 20\u00a0%.<\/li>\n\n\n\n<li>L\u2019annuit\u00e9 d\u2019amortissement est de (18\u00a0000 \u2013\u00a03\u2009000) x 20\u00a0% = 3\u2009000\u00a0\u20ac.<\/li>\n\n\n\n<li>Le premier exercice, l\u2019entreprise comptabilise 270\/360 de l\u2019annuit\u00e9, soit 2\u2009250\u00a0\u20ac.<\/li>\n<\/ul>\n\n\n\n<figure class=\"wp-block-table is-style-stripes\"><table><tbody><tr><td><strong>Exercice<\/strong><\/td><td><strong>Dotation<\/strong><\/td><td><strong>Amortissements cumul\u00e9s<\/strong><\/td><td><strong>Valeur nette comptable<\/strong><\/td><\/tr><tr><td>N<\/td><td>2\u2009250<\/td><td>2\u2009250<\/td><td>15&nbsp;750<\/td><\/tr><tr><td>N+1<\/td><td>3\u2009000<\/td><td>5\u2009250<\/td><td>12&nbsp;750<\/td><\/tr><tr><td>N+&nbsp;2<\/td><td>3\u2009000<\/td><td>8\u2009250<\/td><td>9\u2009750<\/td><\/tr><tr><td>N+3<\/td><td>3\u2009000&nbsp;<\/td><td>11&nbsp;250&nbsp;<\/td><td>6\u2009750<\/td><\/tr><tr><td>N+4<\/td><td>3\u2009000<\/td><td>14&nbsp;250<\/td><td>3\u2009750<\/td><\/tr><tr><td>N+5<\/td><td>750<\/td><td>15&nbsp;000<\/td><td>3\u2009000<\/td><\/tr><\/tbody><\/table><figcaption class=\"wp-element-caption\">Tableau d\u2019amortissement comptable<\/figcaption><\/figure>\n\n\n\n<p>La valeur nette comptable de N+5 correspond \u00e0 la valeur de revente estim\u00e9e.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\">L\u2019amortissement en unit\u00e9s d\u2019\u0153uvres<\/h3>\n\n\n\n<p>Dans le cadre de cette m\u00e9thode, on remplace les ann\u00e9es par le <strong>nombre d\u2019unit\u00e9s que l\u2019actif peut produire<\/strong> au cours de sa dur\u00e9e d\u2019utilisation. L\u2019objectif est d\u2019exprimer au plus juste le rythme de consommation des avantages \u00e9conomiques du bien.<\/p>\n\n\n\n<p>Vous d\u00e9finissez un crit\u00e8re technique pertinent pour chaque nature d\u2019immobilisation. Pour un v\u00e9hicule, vous amortissez sur la base des kilom\u00e8tres parcourus. Pour une machine, vous vous fondez sur le nombre de pi\u00e8ces fabriqu\u00e9es.<\/p>\n\n\n\n<p>Fiscalement, cette m\u00e9thode est applicable dans de rares cas.<\/p>\n\n\n\n<p>Nous vous proposons l\u2019<strong>exemple <\/strong>suivant&nbsp;: le 1<sup>er<\/sup>&nbsp;juin de l\u2019ann\u00e9e N, une entreprise investit 20&nbsp;000&nbsp;\u20ac dans une machine amortie sur 5&nbsp;ans. Ce mat\u00e9riel compose la cha\u00eene de production et devrait produire 250&nbsp;000&nbsp;pi\u00e8ces au total.<\/p>\n\n\n\n<p>L\u2019amortissement unitaire s\u2019\u00e9l\u00e8ve \u00e0 20&nbsp;000\/250&nbsp;000 = 0,08&nbsp;\u20ac.<\/p>\n\n\n\n<p>La dotation annuelle varie en fonction du nombre de pi\u00e8ces produites.<\/p>\n\n\n\n<p>La premi\u00e8re ann\u00e9e, l\u2019entreprise fabrique 25&nbsp;000&nbsp;pi\u00e8ces, soit une annuit\u00e9 d\u2019amortissement de 2\u2009000&nbsp;\u20ac.<\/p>\n\n\n\n<figure class=\"wp-block-table is-style-stripes\"><table><tbody><tr><td><strong>Exercice<\/strong><\/td><td><strong>Nombres de pi\u00e8ces produites<\/strong><\/td><td><strong>Dotation<\/strong><\/td><td><strong>Amortissements cumul\u00e9s<\/strong><\/td><td><strong>Valeur nette comptable<\/strong><\/td><\/tr><tr><td>N<\/td><td>25&nbsp;000<\/td><td>2\u2009000<\/td><td>2\u2009000<\/td><td>18&nbsp;000<\/td><\/tr><tr><td>N+1<\/td><td>53&nbsp;000<\/td><td>4\u2009240<\/td><td>6\u2009240<\/td><td>13&nbsp;760<\/td><\/tr><tr><td>N+&nbsp;2<\/td><td>55&nbsp;000<\/td><td>4\u2009400<\/td><td>10&nbsp;640<\/td><td>9\u2009360<\/td><\/tr><tr><td>N+3<\/td><td>57&nbsp;000<\/td><td>4\u2009560<\/td><td>15&nbsp;200<\/td><td>4\u2009800<\/td><\/tr><tr><td>N+4<\/td><td>60&nbsp;000<\/td><td>4\u2009800<\/td><td>20&nbsp;000<\/td><td>0<\/td><\/tr><tr><td>Total<\/td><td>250&nbsp;000<\/td><td>20&nbsp;000<\/td><td><\/td><td><\/td><\/tr><\/tbody><\/table><figcaption class=\"wp-element-caption\">Tableau d\u2019amortissement comptable<\/figcaption><\/figure>\n\n\n\n<h3 class=\"wp-block-heading\">L\u2019amortissement d\u00e9gressif<\/h3>\n\n\n\n<h4 class=\"wp-block-heading\">La m\u00e9thode d\u00e9gressive<\/h4>\n\n\n\n<p>Par le dispositif de l\u2019amortissement d\u00e9gressif, l\u2019administration fiscale autorise les entreprises \u00e0 constater des <strong>amortissements sup\u00e9rieurs<\/strong> \u00e0 ceux de la m\u00e9thode lin\u00e9aire lors des premi\u00e8res ann\u00e9es d\u2019utilisation du bien.<\/p>\n\n\n\n<p><a href=\"https:\/\/www.legifrance.gouv.fr\/codes\/article_lc\/LEGIARTI000037987291\" target=\"_blank\" rel=\"noreferrer noopener nofollow\">L\u2019article 39&nbsp;A du Code g\u00e9n\u00e9ral des imp\u00f4ts<\/a> liste les actifs neufs concern\u00e9s&nbsp;:&nbsp;<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>les biens d\u2019\u00e9quipement autres que les immeubles d\u2019habitation, les chantiers et les locaux servant \u00e0 l\u2019exercice de la profession, acquis ou fabriqu\u00e9s, par les entreprises industrielles\u00a0;<\/li>\n\n\n\n<li>les investissements h\u00f4teliers\u00a0;<\/li>\n\n\n\n<li>les satellites de communication, etc.<\/li>\n<\/ul>\n\n\n\n<p>Le taux d\u2019amortissement d\u00e9gressif se calcule en appliquant au taux lin\u00e9aire un coefficient de&nbsp;:<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>1,25 pour une dur\u00e9e normale d\u2019utilisation de 3 ou 4\u00a0ans\u00a0;<\/li>\n\n\n\n<li>1,75 pour une dur\u00e9e d\u2019utilisation de 5 ou 6\u00a0ans\u00a0;<\/li>\n\n\n\n<li>2,25 pour une dur\u00e9e sup\u00e9rieure \u00e0 6\u00a0ans.<\/li>\n<\/ul>\n\n\n\n<h4 class=\"wp-block-heading\">Exemple d\u2019amortissement d\u00e9gressif<\/h4>\n\n\n\n<p>Dans cet <strong>exemple<\/strong>, l\u2019entreprise ach\u00e8te un bien de 50&nbsp;000&nbsp;\u20ac amortissable sur 5&nbsp;ans au 01\/01\/N.<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Le taux d\u2019amortissement lin\u00e9aire est de 100\/5 = 20\u00a0%.<\/li>\n\n\n\n<li>La dotation selon la m\u00e9thode lin\u00e9aire est de 10\u00a0000\u00a0\u20ac.<\/li>\n\n\n\n<li>Le taux d\u2019amortissement d\u00e9gressif est de 1,75 x 20\u00a0% = 35\u00a0%.<\/li>\n\n\n\n<li>La dotation selon la m\u00e9thode d\u00e9gressive est de 17\u00a0500\u00a0\u20ac la premi\u00e8re ann\u00e9e.<\/li>\n<\/ul>\n\n\n\n<figure class=\"wp-block-table aligncenter is-style-stripes has-small-font-size\"><table class=\"has-black-color has-white-background-color has-text-color has-background\"><tbody><tr><td><strong>Exercice<\/strong><\/td><td><strong>Amortissement d\u00e9gressif<\/strong><\/td><td><strong>Amortissement lin\u00e9aire<\/strong><\/td><td><strong>Amortissement d\u00e9rogatoire<\/strong><\/td><td><strong>Valeur r\u00e9siduelle<\/strong><\/td><\/tr><tr><td>N<\/td><td>17&nbsp;500<\/td><td>10&nbsp;000<\/td><td>7\u2009500 (1)<\/td><td>32&nbsp;500 (2)<\/td><\/tr><tr><td>N+1<\/td><td>11&nbsp;375 (3)<\/td><td>10&nbsp;000<\/td><td>1\u2009375<\/td><td>21&nbsp;125<\/td><\/tr><tr><td>N+&nbsp;2<\/td><td>7\u2009394<\/td><td>10&nbsp;000<\/td><td>&#8211; 2\u2009606<\/td><td>13&nbsp;731<\/td><\/tr><tr><td>N+3<\/td><td>6\u2009865,5 (4)<\/td><td>10&nbsp;000<\/td><td>&#8211; 3\u2009134,5<\/td><td>6\u2009865,5<\/td><\/tr><tr><td>N+4<\/td><td>6\u2009865,5<\/td><td>10&nbsp;000<\/td><td>&#8211; 3\u2009134,5<\/td><td>0<\/td><\/tr><tr><td>Total<\/td><td>50&nbsp;000<\/td><td>50&nbsp;000<\/td><td>0<\/td><td><\/td><\/tr><\/tbody><\/table><figcaption class=\"wp-element-caption\">Tableau d\u2019amortissement comptable<\/figcaption><\/figure>\n\n\n\n<p>(1) 17&nbsp;500 \u2013&nbsp;10&nbsp;000 = 7\u2009500<\/p>\n\n\n\n<p>(2) 50&nbsp;000 \u2013&nbsp;17&nbsp;500 = 32&nbsp;500<\/p>\n\n\n\n<p>(3) 32&nbsp;500 x 35&nbsp;% = 113 75<\/p>\n\n\n\n<p>(4) En N+3, l\u2019annuit\u00e9 d\u00e9gressive devrait \u00eatre de 13&nbsp;731 x 35&nbsp;% = 4\u2009805,85. Elle est inf\u00e9rieure \u00e0 l\u2019annuit\u00e9 calcul\u00e9e sur la valeur r\u00e9siduelle divis\u00e9e par la dur\u00e9e d\u2019utilisation restant \u00e0 courir&nbsp;: 13&nbsp;731\/2 = 6\u2009865,5. L\u2019entreprise peut donc constater un amortissement lin\u00e9aire les 2&nbsp;derni\u00e8res ann\u00e9es.<\/p>\n\n\n\n<h4 class=\"wp-block-heading\">Comptabilisation de l\u2019amortissement comptable<\/h4>\n\n\n\n<p>L\u2019amortissement comptable est enregistr\u00e9 au moment des op\u00e9rations de cl\u00f4ture de l\u2019exercice. Il s\u2019appuie sur les montants inscrits au plan d\u2019amortissement.&nbsp;<\/p>\n\n\n\n<p>Les comptes comptables impact\u00e9s par cette saisie sont&nbsp;:&nbsp;<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>les comptes\u00a068 de dotations aux amortissements au d\u00e9bit\u00a0;<\/li>\n\n\n\n<li>les comptes\u00a028 d\u2019amortissements des immobilisations au cr\u00e9dit.<\/li>\n<\/ul>\n\n\n\n<h2 class=\"wp-block-heading\">Diff\u00e9rences entre amortissement comptable et fiscal&nbsp;: le cas de l\u2019amortissement d\u00e9rogatoire<\/h2>\n\n\n\n<p>Les r\u00e8gles comptables et fiscales diff\u00e8rent en mati\u00e8re d\u2019amortissement. Parfois, l\u2019amortissement comptabilis\u00e9 n\u2019est pas fiscalement d\u00e9ductible, ou \u00e0 l\u2019inverse, l\u2019entreprise a le droit de constater une dotation sup\u00e9rieure. \u00c0 l\u2019origine de ces divergences, on trouve&nbsp;:&nbsp;<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>une dur\u00e9e d\u2019amortissement fiscal inf\u00e9rieure \u00e0 la dur\u00e9e comptable comme pour les amortissements exceptionnels\u00a0;<\/li>\n\n\n\n<li>la prise en compte de la dur\u00e9e r\u00e9elle d\u2019utilisation du bien en comptabilit\u00e9 et de la dur\u00e9e d\u2019usage en fiscalit\u00e9\u00a0;<\/li>\n\n\n\n<li>une m\u00e9thode d\u2019amortissement diff\u00e9rente (en unit\u00e9s d\u2019\u0153uvre en comptabilit\u00e9 et lin\u00e9aire pour la partie fiscale)\u00a0;<\/li>\n\n\n\n<li>la d\u00e9duction de la valeur r\u00e9siduelle estim\u00e9e en comptabilit\u00e9, non admise dans les d\u00e9clarations fiscales.<\/li>\n<\/ul>\n\n\n\n<p>L\u2019entreprise doit alors enregistrer un <strong>amortissement d\u00e9rogatoire<\/strong> sous la forme d\u2019une dotation aux provisions r\u00e9glement\u00e9es. Il est dot\u00e9 les premi\u00e8res ann\u00e9es, puis fait l\u2019objet d\u2019une reprise aux exercices suivants. Dans l\u2019exemple d\u2019amortissement d\u00e9gressif ci-dessus, pendant les 2&nbsp;premi\u00e8res ann\u00e9es, l\u2019entreprise saisit une dotation aux provisions r\u00e9glement\u00e9es. Puis, de N+2 \u00e0 N+4, elle comptabilise la reprise.<\/p>\n\n\n\n<p>L\u2019<a href=\"https:\/\/rfcomptable.grouperf.com\/article\/0335\/ms\/rfcompms0335_4056.html\" target=\"_blank\" rel=\"noreferrer noopener nofollow\">amortissement d\u00e9rogatoire<\/a> est consid\u00e9r\u00e9 comme une charge ou un produit exceptionnel. Il n\u2019impacte pas le r\u00e9sultat d\u2019exploitation.<\/p>\n\n\n\n<p>Poursuivez votre lecture et apprenez-en plus sur <a href=\"https:\/\/ipaidthat.io\/mag\/comptabilite\/quest-ce-que-limputation-comptable-dune-entreprise\/\" target=\"_blank\" rel=\"noreferrer noopener\">l\u2019imputation comptable&nbsp;<\/a>!<\/p>\n\n\n\n<p class=\"has-text-align-center\"><strong>iPaidThat vous facilite la t\u00e2che. Notre suite logicielle automatise et facilite votre gestion comptable et financi\u00e8re en un rien de temps !<\/strong><\/p>\n\n\n\n<div class=\"wp-block-buttons is-content-justification-center is-layout-flex wp-container-core-buttons-is-layout-a89b3969 wp-block-buttons-is-layout-flex\">\n<div class=\"wp-block-button\"><a class=\"wp-block-button__link has-background wp-element-button\" style=\"background-color:#ff3c3c\"><strong>D\u00e9couvrez la solution iPaidThat<\/strong><\/a><\/div>\n<\/div>\n\n\n\n<p><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Les investissements, qui ont pour but de d\u00e9velopper votre activit\u00e9, de produire des avantages \u00e9conomiques \u00e0 moyen et long termes, s\u2019enregistrent \u00e0 l\u2019actif de votre bilan, au niveau des immobilisations. Tous les ans, au moment de la cl\u00f4ture de l\u2019exercice, vous devez saisir dans votre comptabilit\u00e9 leur perte de valeur sous forme d\u2019amortissement comptable. Quelle [&hellip;]<\/p>\n","protected":false},"author":4,"featured_media":18755,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[5],"tags":[],"class_list":["post-12373","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-comptabilite"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v26.6 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Amortissement comptable\u00a0: comprendre, calculer et comptabiliser<\/title>\n<meta name=\"description\" content=\"Lin\u00e9aire, progressif ou exceptionnel, comprenez ce qu\u2019est l\u2019amortissement comptable : actifs concern\u00e9s, base, dur\u00e9e, m\u00e9thode de calcul et \u00e9criture.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/app.ipaidthat.io\/mag\/comptabilite\/lamortissement-comptable-comprendre-calculer-et-comptabiliser\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Amortissement comptable\u00a0: comprendre, calculer et comptabiliser\" \/>\n<meta property=\"og:description\" content=\"Lin\u00e9aire, progressif ou exceptionnel, comprenez ce qu\u2019est l\u2019amortissement comptable : actifs concern\u00e9s, base, dur\u00e9e, m\u00e9thode de calcul et \u00e9criture.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/app.ipaidthat.io\/mag\/comptabilite\/lamortissement-comptable-comprendre-calculer-et-comptabiliser\/\" \/>\n<meta property=\"og:site_name\" content=\"iPaidThat Mag\" \/>\n<meta property=\"article:published_time\" content=\"2022-10-25T08:05:00+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2025-12-29T10:51:51+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/app.ipaidthat.io\/mag\/wp-content\/uploads\/2019\/07\/avantage-externaliser-administrative.png\" \/>\n\t<meta property=\"og:image:width\" content=\"1024\" \/>\n\t<meta property=\"og:image:height\" content=\"768\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"S\u00e9bastien Claeys\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"S\u00e9bastien Claeys\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"11 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/app.ipaidthat.io\/mag\/comptabilite\/lamortissement-comptable-comprendre-calculer-et-comptabiliser\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/app.ipaidthat.io\/mag\/comptabilite\/lamortissement-comptable-comprendre-calculer-et-comptabiliser\/\"},\"author\":{\"name\":\"S\u00e9bastien Claeys\",\"@id\":\"https:\/\/app.ipaidthat.io\/mag\/#\/schema\/person\/021144662586a12df79c88913050baaa\"},\"headline\":\"L\u2019amortissement comptable : comprendre, calculer et comptabiliser\",\"datePublished\":\"2022-10-25T08:05:00+00:00\",\"dateModified\":\"2025-12-29T10:51:51+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/app.ipaidthat.io\/mag\/comptabilite\/lamortissement-comptable-comprendre-calculer-et-comptabiliser\/\"},\"wordCount\":2234,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/app.ipaidthat.io\/mag\/#organization\"},\"image\":{\"@id\":\"https:\/\/app.ipaidthat.io\/mag\/comptabilite\/lamortissement-comptable-comprendre-calculer-et-comptabiliser\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/app.ipaidthat.io\/mag\/wp-content\/uploads\/2019\/07\/avantage-externaliser-administrative.png\",\"articleSection\":[\"Comptabilit\u00e9\"],\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/app.ipaidthat.io\/mag\/comptabilite\/lamortissement-comptable-comprendre-calculer-et-comptabiliser\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/app.ipaidthat.io\/mag\/comptabilite\/lamortissement-comptable-comprendre-calculer-et-comptabiliser\/\",\"url\":\"https:\/\/app.ipaidthat.io\/mag\/comptabilite\/lamortissement-comptable-comprendre-calculer-et-comptabiliser\/\",\"name\":\"Amortissement comptable\u00a0: comprendre, calculer et comptabiliser\",\"isPartOf\":{\"@id\":\"https:\/\/app.ipaidthat.io\/mag\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/app.ipaidthat.io\/mag\/comptabilite\/lamortissement-comptable-comprendre-calculer-et-comptabiliser\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/app.ipaidthat.io\/mag\/comptabilite\/lamortissement-comptable-comprendre-calculer-et-comptabiliser\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/app.ipaidthat.io\/mag\/wp-content\/uploads\/2019\/07\/avantage-externaliser-administrative.png\",\"datePublished\":\"2022-10-25T08:05:00+00:00\",\"dateModified\":\"2025-12-29T10:51:51+00:00\",\"description\":\"Lin\u00e9aire, progressif ou exceptionnel, comprenez ce qu\u2019est l\u2019amortissement comptable : actifs concern\u00e9s, base, dur\u00e9e, m\u00e9thode de calcul et \u00e9criture.\",\"breadcrumb\":{\"@id\":\"https:\/\/app.ipaidthat.io\/mag\/comptabilite\/lamortissement-comptable-comprendre-calculer-et-comptabiliser\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/app.ipaidthat.io\/mag\/comptabilite\/lamortissement-comptable-comprendre-calculer-et-comptabiliser\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/app.ipaidthat.io\/mag\/comptabilite\/lamortissement-comptable-comprendre-calculer-et-comptabiliser\/#primaryimage\",\"url\":\"https:\/\/app.ipaidthat.io\/mag\/wp-content\/uploads\/2019\/07\/avantage-externaliser-administrative.png\",\"contentUrl\":\"https:\/\/app.ipaidthat.io\/mag\/wp-content\/uploads\/2019\/07\/avantage-externaliser-administrative.png\",\"width\":1024,\"height\":768,\"caption\":\"avantage-externaliser-administrative\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/app.ipaidthat.io\/mag\/comptabilite\/lamortissement-comptable-comprendre-calculer-et-comptabiliser\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Le Mag\",\"item\":\"https:\/\/app.ipaidthat.io\/mag\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Comptabilit\u00e9\",\"item\":\"https:\/\/app.ipaidthat.io\/mag\/category\/comptabilite\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"L\u2019amortissement comptable : comprendre, calculer et comptabiliser\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/app.ipaidthat.io\/mag\/#website\",\"url\":\"https:\/\/app.ipaidthat.io\/mag\/\",\"name\":\"IPaidThat Mag\",\"description\":\"Une gestion simple, automatis\u00e9e et collaborative\",\"publisher\":{\"@id\":\"https:\/\/app.ipaidthat.io\/mag\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/app.ipaidthat.io\/mag\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/app.ipaidthat.io\/mag\/#organization\",\"name\":\"IPaidThat Mag\",\"url\":\"https:\/\/app.ipaidthat.io\/mag\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/app.ipaidthat.io\/mag\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/app.ipaidthat.io\/mag\/wp-content\/uploads\/2025\/11\/logo-le-mag-blog-ipaidthat.png\",\"contentUrl\":\"https:\/\/app.ipaidthat.io\/mag\/wp-content\/uploads\/2025\/11\/logo-le-mag-blog-ipaidthat.png\",\"width\":1817,\"height\":524,\"caption\":\"IPaidThat Mag\"},\"image\":{\"@id\":\"https:\/\/app.ipaidthat.io\/mag\/#\/schema\/logo\/image\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\/\/app.ipaidthat.io\/mag\/#\/schema\/person\/021144662586a12df79c88913050baaa\",\"name\":\"S\u00e9bastien Claeys\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/app.ipaidthat.io\/mag\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/app.ipaidthat.io\/mag\/wp-content\/uploads\/2023\/02\/sebastien-clayes-ipaidthat-96x96.png\",\"contentUrl\":\"https:\/\/app.ipaidthat.io\/mag\/wp-content\/uploads\/2023\/02\/sebastien-clayes-ipaidthat-96x96.png\",\"caption\":\"S\u00e9bastien Claeys\"},\"url\":\"https:\/\/app.ipaidthat.io\/mag\/author\/sebastienipaidthat-io\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Amortissement comptable\u00a0: comprendre, calculer et comptabiliser","description":"Lin\u00e9aire, progressif ou exceptionnel, comprenez ce qu\u2019est l\u2019amortissement comptable : actifs concern\u00e9s, base, dur\u00e9e, m\u00e9thode de calcul et \u00e9criture.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/app.ipaidthat.io\/mag\/comptabilite\/lamortissement-comptable-comprendre-calculer-et-comptabiliser\/","og_locale":"fr_FR","og_type":"article","og_title":"Amortissement comptable\u00a0: comprendre, calculer et comptabiliser","og_description":"Lin\u00e9aire, progressif ou exceptionnel, comprenez ce qu\u2019est l\u2019amortissement comptable : actifs concern\u00e9s, base, dur\u00e9e, m\u00e9thode de calcul et \u00e9criture.","og_url":"https:\/\/app.ipaidthat.io\/mag\/comptabilite\/lamortissement-comptable-comprendre-calculer-et-comptabiliser\/","og_site_name":"iPaidThat Mag","article_published_time":"2022-10-25T08:05:00+00:00","article_modified_time":"2025-12-29T10:51:51+00:00","og_image":[{"width":1024,"height":768,"url":"https:\/\/app.ipaidthat.io\/mag\/wp-content\/uploads\/2019\/07\/avantage-externaliser-administrative.png","type":"image\/png"}],"author":"S\u00e9bastien Claeys","twitter_card":"summary_large_image","twitter_misc":{"\u00c9crit par":"S\u00e9bastien Claeys","Dur\u00e9e de lecture estim\u00e9e":"11 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/app.ipaidthat.io\/mag\/comptabilite\/lamortissement-comptable-comprendre-calculer-et-comptabiliser\/#article","isPartOf":{"@id":"https:\/\/app.ipaidthat.io\/mag\/comptabilite\/lamortissement-comptable-comprendre-calculer-et-comptabiliser\/"},"author":{"name":"S\u00e9bastien Claeys","@id":"https:\/\/app.ipaidthat.io\/mag\/#\/schema\/person\/021144662586a12df79c88913050baaa"},"headline":"L\u2019amortissement comptable : comprendre, calculer et comptabiliser","datePublished":"2022-10-25T08:05:00+00:00","dateModified":"2025-12-29T10:51:51+00:00","mainEntityOfPage":{"@id":"https:\/\/app.ipaidthat.io\/mag\/comptabilite\/lamortissement-comptable-comprendre-calculer-et-comptabiliser\/"},"wordCount":2234,"commentCount":0,"publisher":{"@id":"https:\/\/app.ipaidthat.io\/mag\/#organization"},"image":{"@id":"https:\/\/app.ipaidthat.io\/mag\/comptabilite\/lamortissement-comptable-comprendre-calculer-et-comptabiliser\/#primaryimage"},"thumbnailUrl":"https:\/\/app.ipaidthat.io\/mag\/wp-content\/uploads\/2019\/07\/avantage-externaliser-administrative.png","articleSection":["Comptabilit\u00e9"],"inLanguage":"fr-FR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/app.ipaidthat.io\/mag\/comptabilite\/lamortissement-comptable-comprendre-calculer-et-comptabiliser\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/app.ipaidthat.io\/mag\/comptabilite\/lamortissement-comptable-comprendre-calculer-et-comptabiliser\/","url":"https:\/\/app.ipaidthat.io\/mag\/comptabilite\/lamortissement-comptable-comprendre-calculer-et-comptabiliser\/","name":"Amortissement comptable\u00a0: comprendre, calculer et comptabiliser","isPartOf":{"@id":"https:\/\/app.ipaidthat.io\/mag\/#website"},"primaryImageOfPage":{"@id":"https:\/\/app.ipaidthat.io\/mag\/comptabilite\/lamortissement-comptable-comprendre-calculer-et-comptabiliser\/#primaryimage"},"image":{"@id":"https:\/\/app.ipaidthat.io\/mag\/comptabilite\/lamortissement-comptable-comprendre-calculer-et-comptabiliser\/#primaryimage"},"thumbnailUrl":"https:\/\/app.ipaidthat.io\/mag\/wp-content\/uploads\/2019\/07\/avantage-externaliser-administrative.png","datePublished":"2022-10-25T08:05:00+00:00","dateModified":"2025-12-29T10:51:51+00:00","description":"Lin\u00e9aire, progressif ou exceptionnel, comprenez ce qu\u2019est l\u2019amortissement comptable : actifs concern\u00e9s, base, dur\u00e9e, m\u00e9thode de calcul et \u00e9criture.","breadcrumb":{"@id":"https:\/\/app.ipaidthat.io\/mag\/comptabilite\/lamortissement-comptable-comprendre-calculer-et-comptabiliser\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/app.ipaidthat.io\/mag\/comptabilite\/lamortissement-comptable-comprendre-calculer-et-comptabiliser\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/app.ipaidthat.io\/mag\/comptabilite\/lamortissement-comptable-comprendre-calculer-et-comptabiliser\/#primaryimage","url":"https:\/\/app.ipaidthat.io\/mag\/wp-content\/uploads\/2019\/07\/avantage-externaliser-administrative.png","contentUrl":"https:\/\/app.ipaidthat.io\/mag\/wp-content\/uploads\/2019\/07\/avantage-externaliser-administrative.png","width":1024,"height":768,"caption":"avantage-externaliser-administrative"},{"@type":"BreadcrumbList","@id":"https:\/\/app.ipaidthat.io\/mag\/comptabilite\/lamortissement-comptable-comprendre-calculer-et-comptabiliser\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Le Mag","item":"https:\/\/app.ipaidthat.io\/mag\/"},{"@type":"ListItem","position":2,"name":"Comptabilit\u00e9","item":"https:\/\/app.ipaidthat.io\/mag\/category\/comptabilite\/"},{"@type":"ListItem","position":3,"name":"L\u2019amortissement comptable : comprendre, calculer et comptabiliser"}]},{"@type":"WebSite","@id":"https:\/\/app.ipaidthat.io\/mag\/#website","url":"https:\/\/app.ipaidthat.io\/mag\/","name":"IPaidThat Mag","description":"Une gestion simple, automatis\u00e9e et collaborative","publisher":{"@id":"https:\/\/app.ipaidthat.io\/mag\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/app.ipaidthat.io\/mag\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/app.ipaidthat.io\/mag\/#organization","name":"IPaidThat Mag","url":"https:\/\/app.ipaidthat.io\/mag\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/app.ipaidthat.io\/mag\/#\/schema\/logo\/image\/","url":"https:\/\/app.ipaidthat.io\/mag\/wp-content\/uploads\/2025\/11\/logo-le-mag-blog-ipaidthat.png","contentUrl":"https:\/\/app.ipaidthat.io\/mag\/wp-content\/uploads\/2025\/11\/logo-le-mag-blog-ipaidthat.png","width":1817,"height":524,"caption":"IPaidThat Mag"},"image":{"@id":"https:\/\/app.ipaidthat.io\/mag\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/app.ipaidthat.io\/mag\/#\/schema\/person\/021144662586a12df79c88913050baaa","name":"S\u00e9bastien Claeys","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/app.ipaidthat.io\/mag\/#\/schema\/person\/image\/","url":"https:\/\/app.ipaidthat.io\/mag\/wp-content\/uploads\/2023\/02\/sebastien-clayes-ipaidthat-96x96.png","contentUrl":"https:\/\/app.ipaidthat.io\/mag\/wp-content\/uploads\/2023\/02\/sebastien-clayes-ipaidthat-96x96.png","caption":"S\u00e9bastien Claeys"},"url":"https:\/\/app.ipaidthat.io\/mag\/author\/sebastienipaidthat-io\/"}]}},"_links":{"self":[{"href":"https:\/\/app.ipaidthat.io\/mag\/wp-json\/wp\/v2\/posts\/12373","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/app.ipaidthat.io\/mag\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/app.ipaidthat.io\/mag\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/app.ipaidthat.io\/mag\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/app.ipaidthat.io\/mag\/wp-json\/wp\/v2\/comments?post=12373"}],"version-history":[{"count":2,"href":"https:\/\/app.ipaidthat.io\/mag\/wp-json\/wp\/v2\/posts\/12373\/revisions"}],"predecessor-version":[{"id":18777,"href":"https:\/\/app.ipaidthat.io\/mag\/wp-json\/wp\/v2\/posts\/12373\/revisions\/18777"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/app.ipaidthat.io\/mag\/wp-json\/wp\/v2\/media\/18755"}],"wp:attachment":[{"href":"https:\/\/app.ipaidthat.io\/mag\/wp-json\/wp\/v2\/media?parent=12373"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/app.ipaidthat.io\/mag\/wp-json\/wp\/v2\/categories?post=12373"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/app.ipaidthat.io\/mag\/wp-json\/wp\/v2\/tags?post=12373"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}