{"id":11688,"date":"2022-08-10T12:05:00","date_gmt":"2022-08-10T10:05:00","guid":{"rendered":"https:\/\/ipaidthat.io\/mag\/?p=11688"},"modified":"2022-08-10T12:05:00","modified_gmt":"2022-08-10T10:05:00","slug":"plan-comptable-general-le-guide-pour-la-tenue-de-votre-comptabilite","status":"publish","type":"post","link":"https:\/\/app.ipaidthat.io\/mag\/featured\/plan-comptable-general-le-guide-pour-la-tenue-de-votre-comptabilite\/","title":{"rendered":"Plan comptable g\u00e9n\u00e9ral : La tenue de votre comptabilit\u00e9"},"content":{"rendered":"\n<p>Selon le Code de commerce, toute personne physique ou morale ayant la qualit\u00e9 de commer\u00e7ant doit enregistrer chronologiquement les op\u00e9rations li\u00e9es \u00e0 son activit\u00e9 et \u00e9tablir des comptes annuels \u00e0 la cl\u00f4ture de son exercice. En France, la tenue de la comptabilit\u00e9 est encadr\u00e9e par la loi et doit se conformer aux r\u00e8gles \u00e9nonc\u00e9es dans le plan comptable g\u00e9n\u00e9ral (PCG).<\/p>\n\n\n\n<p>Principes de la comptabilit\u00e9, documents de synth\u00e8se, classe de comptes, livres comptables obligatoires sont autant de notions abord\u00e9es dans ce r\u00e8glement produit par l\u2019ANC.<\/p>\n\n\n\n<p>Qu\u2019est-ce que le PCG&nbsp;? Quelles sont les entreprises soumises \u00e0 son application&nbsp;? \u00c0 quoi sert-il&nbsp;? D\u00e9couvrez en d\u00e9tail la composition du plan comptable g\u00e9n\u00e9ral.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">Qu\u2019est-ce que le plan comptable g\u00e9n\u00e9ral (PCG)&nbsp;?&nbsp;<\/h2>\n\n\n\n<p>Le plan comptable g\u00e9n\u00e9ral est un r\u00e8glement \u00e9tabli par l\u2019<a href=\"https:\/\/www.anc.gouv.fr\/sites\/anc\/accueil.html\" target=\"_blank\" rel=\"noreferrer noopener\">Autorit\u00e9 des normes comptables<\/a> qui permet aux entrepreneurs de tenir leur comptabilit\u00e9 dans le respect des normes en vigueur en France. Ce <strong>document de r\u00e9f\u00e9rence<\/strong> aborde les points suivants&nbsp;:&nbsp;<\/p>\n\n\n\n<ul class=\"wp-block-list\"><li>les principes de la comptabilit\u00e9&nbsp;;<\/li><li>les d\u00e9finitions de l\u2019actif et du passif&nbsp;;<\/li><li>les charges et les produits&nbsp;;<\/li><li>les op\u00e9rations de nature sp\u00e9cifique comme les logiciels ou les activit\u00e9s agricoles&nbsp;;<\/li><li>la comptabilisation et l\u2019\u00e9valuation des op\u00e9rations de fusion et assimil\u00e9es&nbsp;;<\/li><li>les documents de synth\u00e8se comptable (bilan, compte de r\u00e9sultat, annexe)&nbsp;;<\/li><li>les classes de comptes.&nbsp;<\/li><\/ul>\n\n\n\n<h2 class=\"wp-block-heading\">\u00c0 qui s\u2019applique le plan comptable g\u00e9n\u00e9ral&nbsp;?<\/h2>\n\n\n\n<p>Toutes les entit\u00e9s concern\u00e9es par les <a href=\"https:\/\/www.legifrance.gouv.fr\/codes\/article_lc\/LEGIARTI000006219304\/\" target=\"_blank\" rel=\"noreferrer noopener\">obligations l\u00e9gales<\/a> concernant les comptes annuels doivent appliquer les directives du plan comptable g\u00e9n\u00e9ral&nbsp;:&nbsp;<\/p>\n\n\n\n<figure class=\"wp-block-table\"><table class=\"has-white-color has-text-color has-background\" style=\"background-color:#ff3c3c\"><tbody><tr><td class=\"has-text-align-center\" data-align=\"center\">les entreprises relevant du groupe des b\u00e9n\u00e9fices industriels et commerciaux (BIC) ;<\/td><\/tr><tr><td class=\"has-text-align-center\" data-align=\"center\">les professions lib\u00e9rales impos\u00e9es au r\u00e9gime des b\u00e9n\u00e9fices non commerciaux (BNC) ;<\/td><\/tr><tr><td class=\"has-text-align-center\" data-align=\"center\">les soci\u00e9t\u00e9s soumises \u00e0 l\u2019imp\u00f4t sur les soci\u00e9t\u00e9s (SARL, SCI, SAS, SA, SASU\u2026).<\/td><\/tr><\/tbody><\/table><\/figure>\n\n\n\n<p>Certains secteurs disposent de leur propre r\u00e9glementation. Ainsi, les banques et les assurances ont un plan comptable particulier. De m\u00eame, les associations et les fondations se r\u00e9f\u00e8rent \u00e0 un plan comptable sp\u00e9cifique \u00e0 leur activit\u00e9 non marchande.<\/p>\n\n\n\n<p>Seules les micro-entreprises sont exclues de ce dispositif. Elles doivent uniquement tenir un livre des recettes encaiss\u00e9es et, le cas \u00e9ch\u00e9ant, un registre des achats. Pour rappel, en vertu de l\u2019<a href=\"https:\/\/www.legifrance.gouv.fr\/codes\/article_lc\/LEGIARTI000019289307\/\">article&nbsp;L123-28 du Code de commerce<\/a>, elles ne doivent pas d\u00e9passer certains seuils de chiffre d\u2019affaires.<\/p>\n\n\n\n<figure class=\"wp-block-table\"><table class=\"has-white-color has-text-color has-background\" style=\"background-color:#ff3c3c\"><tbody><tr><td>176&nbsp;200&nbsp;\u20ac<br><\/td><td>Pour les activit\u00e9s de vente de marchandises, de vente \u00e0 consommer sur place ou \u00e0 emporter et d\u2019h\u00e9bergement<\/td><\/tr><tr><td>72&nbsp;600&nbsp;\u20ac<\/td><td>Pour les prestations de services.<\/td><\/tr><\/tbody><\/table><\/figure>\n\n\n\n<h2 class=\"wp-block-heading\">\u00c0 quoi sert le plan comptable g\u00e9n\u00e9ral&nbsp;?<\/h2>\n\n\n\n<p>Document indispensable, il guide les entreprises dans leur gestion financi\u00e8re et leur organisation administrative. Il indique comment enregistrer leurs \u00e9critures comptables et produire les livres et documents obligatoires.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\">Le plan comptable comme document de r\u00e9f\u00e9rence comptable<\/h3>\n\n\n\n<p>Le plan comptable g\u00e9n\u00e9ral sert de <strong>r\u00e9f\u00e9rence<\/strong> en mati\u00e8re de comptabilit\u00e9 et permet \u00e0 tous les interlocuteurs de se comprendre. Chef d\u2019entreprise, expert-comptable, partenaires financiers ou administration fiscale, ils poss\u00e8dent tous la m\u00eame d\u00e9finition du bilan et du compte de r\u00e9sultat.&nbsp;<\/p>\n\n\n\n<p>L\u2019<strong>harmonisation des pratiques<\/strong> comptables facilite les comparaisons entre les entreprises, les contr\u00f4les des organismes publics ou les analyses financi\u00e8res.<\/p>\n\n\n\n<p class=\"has-text-align-center\"><a href=\"https:\/\/ipaidthat.io\/fr\/?utm_source=mag&amp;utm_campaign=texte&amp;utm_content=texte\"><strong>Manque de temps ? iPaidThat vous aide instantan\u00e9ment \u00e0 y voir plus clair <strong>dans votre tenue comptable<\/strong><\/strong> <strong>!<\/strong><\/a><\/p>\n\n\n\n<figure class=\"wp-block-embed aligncenter is-type-video is-provider-youtube wp-block-embed-youtube wp-embed-aspect-16-9 wp-has-aspect-ratio\"><div class=\"wp-block-embed__wrapper\">\n<iframe title=\"iPaidThat, l&#039;outil de pr\u00e9-comptabilit\u00e9 tout-en-1 pour les dirigeants\" width=\"800\" height=\"450\" src=\"https:\/\/www.youtube.com\/embed\/XLm535z70Zs?feature=oembed\" frameborder=\"0\" allow=\"accelerometer; autoplay; clipboard-write; encrypted-media; gyroscope; picture-in-picture; web-share\" referrerpolicy=\"strict-origin-when-cross-origin\" allowfullscreen><\/iframe>\n<\/div><\/figure>\n\n\n\n<h3 class=\"wp-block-heading\">Guide de l\u2019enregistrement de vos mouvements financiers<\/h3>\n\n\n\n<p>Le plan comptable g\u00e9n\u00e9ral rappelle les principes essentiels de l\u2019\u00e9tablissement des comptes annuels.&nbsp;<\/p>\n\n\n\n<ul class=\"wp-block-list\"><li>La comptabilit\u00e9 de l\u2019entreprise donne une <strong>image fid\u00e8le <\/strong>du patrimoine, de la situation financi\u00e8re et du r\u00e9sultat de l\u2019entreprise \u00e0 chaque exercice.<\/li><li>Elle permet la comparaison entre les p\u00e9riodes dans un souci de continuit\u00e9 de l\u2019activit\u00e9.<\/li><li>Les comptes sont <strong>sinc\u00e8res<\/strong> et r\u00e9guliers.<\/li><li>La prudence est la r\u00e8gle en mati\u00e8re d\u2019\u00e9valuation.<\/li><li>La <strong>permanence des m\u00e9thodes<\/strong> garantit la coh\u00e9rence des informations comptables.<\/li><\/ul>\n\n\n\n<p>En respectant l\u2019ensemble de ces principes, les entreprises proc\u00e8dent \u00e0 l\u2019<strong>enregistrement de leurs mouvements financiers<\/strong>. En fonction de leur nature, les op\u00e9rations rel\u00e8vent de l\u2019actif, du passif, des charges ou des produits. Elles sont class\u00e9es par comptes comptables et regroup\u00e9es en fin d\u2019exercice dans les documents de synth\u00e8se.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\">Mod\u00e8les des documents de synth\u00e8se<\/h3>\n\n\n\n<p>Le plan comptable g\u00e9n\u00e9ral d\u00e9finit les modalit\u00e9s de pr\u00e9sentation des comptes annuels obligatoires pour les entreprises, \u00e0 savoir&nbsp;:&nbsp;<\/p>\n\n\n\n<ul class=\"wp-block-list\"><li>le bilan&nbsp;;<\/li><li>le compte de r\u00e9sultat&nbsp;;&nbsp;<\/li><li>l\u2019annexe.<\/li><\/ul>\n\n\n\n<p>Il fournit diff\u00e9rents mod\u00e8les de tableaux pour le bilan et le compte de r\u00e9sultat. Selon leur taille, les entreprises peuvent adopter le syst\u00e8me de base, abr\u00e9g\u00e9 ou d\u00e9velopp\u00e9. De m\u00eame, le contenu de l\u2019annexe comptable varie en fonction du r\u00e9gime d\u2019imposition et de la taille des personnes physiques ou morales.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">Les classes de comptes du plan comptable g\u00e9n\u00e9ral<\/h2>\n\n\n\n<p>Le plan comptable g\u00e9n\u00e9ral \u2013&nbsp;ou PCG&nbsp;\u2013 se confond avec la notion de plan de comptes, qui regroupe l\u2019ensemble des <strong>comptes comptables<\/strong> dont une entreprise se sert pour enregistrer ses op\u00e9rations financi\u00e8res. Pr\u00e9sent\u00e9 sous forme de livret au format papier ou inclus au sein des logiciels de comptabilit\u00e9, il est organis\u00e9 en <strong>8&nbsp;classes de comptes<\/strong> dont nous vous donnons le d\u00e9tail.<\/p>\n\n\n\n<figure class=\"wp-block-table is-style-regular\"><table class=\"has-background\" style=\"background-color:#fce6ec\"><tbody><tr><td class=\"has-text-align-center\" data-align=\"center\">Les classes de comptes des op\u00e9rations relatives au bilan, de 1 \u00e0 5<\/td><\/tr><tr><td class=\"has-text-align-center\" data-align=\"center\">Les classes de comptes des op\u00e9rations relatives au r\u00e9sultat, de 6 \u00e0 7<\/td><\/tr><tr><td class=\"has-text-align-center\" data-align=\"center\">La classe&nbsp;8 pour r\u00e9pondre aux exigences en lien avec les documents de synth\u00e8se<\/td><\/tr><\/tbody><\/table><figcaption>Les classes du PCG<\/figcaption><\/figure>\n\n\n\n<h3 class=\"wp-block-heading\">La classe&nbsp;1 du PCG&nbsp;: les comptes de capitaux<\/h3>\n\n\n\n<p>Les <a href=\"https:\/\/www.pcg.fr\/0-plan-comptable.php\" target=\"_blank\" rel=\"noreferrer noopener\">comptes<\/a> dont le num\u00e9ro commence par 1 correspondent aux capitaux propres, aux autres fonds propres, aux emprunts et dettes assimil\u00e9s et aux provisions. Il s\u2019agit des <strong>ressources stables<\/strong> de l\u2019entreprise, comme les apports, les subventions d\u2019investissement, les r\u00e9serves ou le r\u00e9sultat.<\/p>\n\n\n\n<p>Voici quelques exemples de la classe&nbsp;1&nbsp;:&nbsp;<\/p>\n\n\n\n<ul class=\"wp-block-list\"><li>101 \u2014 Capital&nbsp;;<\/li><li>106 \u2014 R\u00e9serves&nbsp;;<\/li><li>110 \u2014 Report \u00e0 nouveau (solde cr\u00e9diteur)&nbsp;;<\/li><li>120 \u2014 R\u00e9sultat de l\u2019exercice (b\u00e9n\u00e9fice) et 129 (perte).<\/li><\/ul>\n\n\n\n<h3 class=\"wp-block-heading\">La classe&nbsp;2 du PCG&nbsp;: les comptes d\u2019immobilisations<\/h3>\n\n\n\n<p>La classe&nbsp;2 concerne le <strong>patrimoine<\/strong> de l\u2019entreprise, c\u2019est-\u00e0-dire les actifs immobilis\u00e9s avec les immobilisations corporelles, incorporelles, financi\u00e8res, ainsi que leurs amortissements et d\u00e9pr\u00e9ciations.<\/p>\n\n\n\n<p>Les biens qui figurent dans ce groupe sont d\u00e9tenus durablement. Les titres immobilis\u00e9s sont identifiables et ont une valeur positive pour l\u2019entreprise. Leur but est de cr\u00e9er de la ressource et de servir l\u2019activit\u00e9 dans le temps.<\/p>\n\n\n\n<ol class=\"wp-block-list\"><li>Les <strong>immobilisations corporelles<\/strong> comprennent par exemple les terrains (211), les constructions (213) ou le mat\u00e9riel (2154).<\/li><li>Les <strong>immobilisations incorporelles<\/strong> font \u00e9tat des frais d\u2019\u00e9tablissement (201) ou du fonds de commerce (207).<\/li><li>Les <strong>immobilisations financi\u00e8res<\/strong> en 26 et 27 se rapportent aux titres de participation ou aux d\u00e9p\u00f4ts et cautionnements.<\/li><\/ol>\n\n\n\n<h3 class=\"wp-block-heading\">La classe&nbsp;3 du plan comptable g\u00e9n\u00e9ral&nbsp;: les comptes de stocks et en-cours<\/h3>\n\n\n\n<p>La classe&nbsp;3 enregistre les \u00e9l\u00e9ments destin\u00e9s \u00e0 \u00eatre revendus par l\u2019entit\u00e9 ou consomm\u00e9s en totalit\u00e9 dans la production. Les biens <strong>en<\/strong> <strong>stock<\/strong> sont pr\u00e9sents physiquement dans l\u2019entreprise, mais ne participent pas encore au cycle d\u2019exploitation,&nbsp;comme&nbsp;:&nbsp;<\/p>\n\n\n\n<ul class=\"wp-block-list\"><li>les mati\u00e8res premi\u00e8res (31)&nbsp;;<\/li><li>les marchandises (37)&nbsp;;<\/li><li>les en-cours de production de biens (33).<\/li><\/ul>\n\n\n\n<h3 class=\"wp-block-heading\">La classe&nbsp;4 du PCG&nbsp;: les comptes de tiers<\/h3>\n\n\n\n<p>Fournisseurs (40), clients (41), personnel (42), organismes sociaux (43), \u00c9tat et collectivit\u00e9s publiques (44), associ\u00e9s (45)\u2026, les personnes physiques ou morales, publiques ou priv\u00e9es qui interagissent avec l\u2019entreprise sont r\u00e9pertori\u00e9es dans les comptes de classe&nbsp;4.<\/p>\n\n\n\n<p>La classe&nbsp;4 correspond aux cr\u00e9anciers et d\u00e9biteurs de l\u2019entit\u00e9.&nbsp;<\/p>\n\n\n\n<h3 class=\"wp-block-heading\">La classe&nbsp;5 du PCG&nbsp;: les comptes financiers<\/h3>\n\n\n\n<p>En classe&nbsp;5, les entreprises comptabilisent les mouvements financiers qui affectent leurs comptes en banque (512) ou la caisse (53). Ch\u00e8ques, esp\u00e8ces, virements, tous les moyens de paiement sont pris en compte.&nbsp;<\/p>\n\n\n\n<p>Les valeurs mobili\u00e8res de placement (50) font \u00e9galement partie de cette classe.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\">La classe&nbsp;6 du PCG&nbsp;: les comptes de charges<\/h3>\n\n\n\n<p>Les <strong>charges<\/strong> sont, avec les produits, des composantes du compte de r\u00e9sultat. Il s\u2019agit d\u2019op\u00e9rations qui impactent n\u00e9gativement le r\u00e9sultat et entra\u00eenent une sortie d\u2019argent&nbsp;:<\/p>\n\n\n\n<ul class=\"wp-block-list\"><li>les achats de marchandises ou de mati\u00e8res premi\u00e8res (60)&nbsp;;<\/li><li>les prestations de services (60)&nbsp;;<\/li><li>les autres charges externes (61 et 62)&nbsp;;<\/li><li>les imp\u00f4ts et taxes (63)&nbsp;;<\/li><li>les charges de personnel (64)&nbsp;;<\/li><li>les charges de gestion courante (65)&nbsp;;<\/li><li>les charges financi\u00e8res (66)&nbsp;;&nbsp;<\/li><li>les charges exceptionnelles (67), etc.<\/li><\/ul>\n\n\n\n<p>Certaines charges n\u2019entra\u00eenent pas de sortie d\u2019argent comme les dotations aux amortissements et d\u00e9pr\u00e9ciations ou aux dotations aux provisions (68).<\/p>\n\n\n\n<h3 class=\"wp-block-heading\">La classe&nbsp;7 du plan comptable g\u00e9n\u00e9ral&nbsp;: les comptes de produits<\/h3>\n\n\n\n<p>La classe&nbsp;7 d\u00e9signe les <strong>produits <\/strong>de l\u2019entreprise, les op\u00e9rations destin\u00e9es \u00e0 augmenter le chiffre d\u2019affaires, \u00e0 couvrir les charges et \u00e0 d\u00e9gager un b\u00e9n\u00e9fice. Elle figure \u00e0 la droite du compte de r\u00e9sultat.<\/p>\n\n\n\n<p>Les ventes de produits fabriqu\u00e9s, des prestations de services ou de marchandises (70) contribuent \u00e0 enrichir l\u2019entit\u00e9 tout comme les subventions d\u2019exploitation (74) ou les produits financiers (76).<\/p>\n\n\n\n<p>On distingue 3&nbsp;cat\u00e9gories de produits&nbsp;:<\/p>\n\n\n\n<ul class=\"wp-block-list\"><li>les produits d\u2019exploitation, qui correspondent \u00e0 l\u2019activit\u00e9 principale de l\u2019entreprise&nbsp;;<\/li><li>les produits financiers en contrepartie de placements&nbsp;;<\/li><li>les produits exceptionnels, qui sont li\u00e9s \u00e0 une op\u00e9ration peu courante.<\/li><\/ul>\n\n\n\n<h3 class=\"wp-block-heading\">La classe&nbsp;8 du PCG&nbsp;: les comptes sp\u00e9ciaux<\/h3>\n\n\n\n<p>La classe&nbsp;8 enregistre les <strong>engagements<\/strong> donn\u00e9s et re\u00e7us par l\u2019entit\u00e9 comme les cautions, les garanties ou les redevances de cr\u00e9dit-bail (801 et 802). Le compte&nbsp;88 est d\u00e9di\u00e9 plus sp\u00e9cifiquement au r\u00e9sultat en instance d\u2019affectation.<\/p>\n\n\n\n<h4 class=\"wp-block-heading\">Le fonctionnement des classes de comptes<\/h4>\n\n\n\n<p>Vous pouvez vous r\u00e9f\u00e9rer au plan comptable achet\u00e9 au format papier ou pr\u00e9sent dans votre logiciel de comptabilit\u00e9. Chaque classe est subdivis\u00e9e en sous-classes afin de satisfaire aux besoins plus ou moins pr\u00e9cis des entreprises.<\/p>\n\n\n\n<p>Le compte&nbsp;40 comptabilise les op\u00e9rations avec vos fournisseurs. Si vous achetez un bien, il doit figurer en 4011 \u2013&nbsp;fournisseurs, achats de biens et prestations de services. Vous \u00eates libre de cr\u00e9er de nouvelles subdivisions afin de distinguer par exemple vos fournisseurs&nbsp;entre eux&nbsp;: Martin en 401101, Dupont en 401102, <\/p>\n\n\n\n<h2 class=\"wp-block-heading\">Le plan comptable g\u00e9n\u00e9ral&nbsp;: outil d\u2019organisation de la comptabilit\u00e9<\/h2>\n\n\n\n<p>Le plan comptable g\u00e9n\u00e9ral ne vous permet pas seulement d\u2019associer une op\u00e9ration financi\u00e8re \u00e0 un compte comptable, il vous aide aussi \u00e0 organiser la tenue de votre comptabilit\u00e9.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\">Les principes d\u2019organisation pr\u00e9conis\u00e9s par le PCG<\/h3>\n\n\n\n<p>Le plan comptable g\u00e9n\u00e9ral pr\u00e9conise de cr\u00e9er des <strong>proc\u00e9dures<\/strong> facilitant le traitement comptable pour l\u2019ensemble de votre personnel. Le recours \u00e0 un <strong>logiciel de comptabilit\u00e9<\/strong> contribue \u00e0 s\u00e9curiser vos enregistrements. Notre solution logicielle propose de prendre en charge, de mani\u00e8re automatiser et compl\u00e8te, la collecte des factures et le transfert de vos donn\u00e9es \u00e0 votre expert-comptable gr\u00e2ce \u00e0 un export au format souhait\u00e9.&nbsp;<\/p>\n\n\n\n<p class=\"has-text-align-center\"><strong>Le <a href=\"https:\/\/ipaidthat.io\/fr\/?utm_source=mag&amp;utm_campaign=texte&amp;utm_content=texte\">logiciel de pr\u00e9-comptabilit\u00e9 iPaidThat<\/a> int\u00e8gre un plan comptable par d\u00e9faut. Votre comptable a le choix entre t\u00e9l\u00e9charger le plan comptable en vigueur ou importer celui de votre entreprise. L\u2019objectif est d\u2019automatiser toujours davantage votre gestion administrative, afin d&rsquo;y passer le moins de temps.<\/strong><\/p>\n\n\n\n<figure class=\"wp-block-image size-full\"><a href=\"https:\/\/ipaidthat.io\/fr\/?utm_source=mag&amp;utm_campaign=banniere&amp;utm_content=banniere\"><img decoding=\"async\" src=\"https:\/\/ipaidthat.io\/mag\/wp-content\/uploads\/2022\/03\/banniere_mag_blog_compta_8.png\" alt=\"banni\u00e8re_mag_blog_compta_8\" class=\"wp-image-9415\"\/><\/a><\/figure>\n\n\n\n<h3 class=\"wp-block-heading\">Les livres comptables obligatoires<\/h3>\n\n\n\n<p>Les entreprises ont parmi leurs obligations l\u00e9gales la tenue de 2&nbsp;<a href=\"https:\/\/ipaidthat.io\/mag\/comptabilite\/quels-livres-comptables-sont-obligatoires-en-entreprise\/\" target=\"_blank\" rel=\"noreferrer noopener\">livres comptables<\/a>&nbsp;:<\/p>\n\n\n\n<ul class=\"wp-block-list\"><li>le livre-journal, qui enregistre les op\u00e9rations au quotidien dans l\u2019ordre chronologique&nbsp;;<\/li><li>le grand livre, qui comporte toutes les \u00e9critures du livre-journal, ventil\u00e9es selon le plan de comptes de l\u2019entit\u00e9.<\/li><\/ul>\n\n\n\n<p>Le livre-journal centralise l\u2019ensemble des \u00e9critures de l\u2019exercice. En fonction de la taille de votre entreprise, vous pouvez choisir de compl\u00e9ter des journaux auxiliaires par types d\u2019op\u00e9rations&nbsp;: achats, ventes, banque, caisse et op\u00e9rations diverses.<\/p>\n\n\n\n<p>Les espaces vides, ratures et alt\u00e9rations sont interdits. Toute modification doit faire l\u2019objet d\u2019une \u00e9criture de contrepassation.<\/p>\n\n\n\n<p>Depuis le 1<sup>er<\/sup>&nbsp;janvier&nbsp;2016, le livre d\u2019inventaire ne fait plus partie des livres comptables obligatoires.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\">Le syst\u00e8me d\u2019enregistrement et les pi\u00e8ces justificatives<\/h3>\n\n\n\n<p>Le plan comptable g\u00e9n\u00e9ral rappelle le principe d\u2019enregistrement des \u00e9critures comptables en \u00ab&nbsp;<strong><a href=\"https:\/\/ipaidthat.io\/mag\/featured\/comptabilite-partie-double\/\" target=\"_blank\" rel=\"noreferrer noopener\">partie double<\/a>&nbsp;\u00bb<\/strong>. Un achat de marchandises aupr\u00e8s d\u2019un fournisseur impacte un compte fournisseur au cr\u00e9dit et un compte de charge au d\u00e9bit pour le m\u00eame montant (dans le cas d\u2019une op\u00e9ration non soumise \u00e0 la TVA).<\/p>\n\n\n\n<p>Les mouvements financiers sont enregistr\u00e9s <strong>chronologiquement<\/strong> et pr\u00e9sentent un caract\u00e8re <strong>d\u00e9finitif <\/strong>et <strong>intangible<\/strong>. Ils font r\u00e9f\u00e9rence \u00e0 une <strong>pi\u00e8ce justificative<\/strong> dat\u00e9e, \u00e9tablie au format papier ou \u00e9lectronique.<\/p>\n\n\n\n<p>Les pi\u00e8ces justificatives (factures, bons de commande, relev\u00e9s bancaires, etc.) constituent une preuve de la r\u00e9alit\u00e9 des op\u00e9rations financi\u00e8res et doivent \u00eatre <a href=\"https:\/\/ipaidthat.io\/mag\/featured\/combien-de-temps-garder-les-factures\/\" target=\"_blank\" rel=\"noreferrer noopener\">conserv\u00e9es<\/a> pendant 10&nbsp;ans. Le mode de conservation doit permettre de <strong>pr\u00e9server<\/strong> le document dans de bonnes conditions afin de pouvoir le fournir en cas de contr\u00f4le par l\u2019administration fiscale ou sur demande de consultation par votre expert-comptable.&nbsp;<\/p>\n\n\n\n<p>Le plan comptable g\u00e9n\u00e9ral est un <strong>document de r\u00e9f\u00e9rence<\/strong> pour toutes les entreprises qui doivent tenir une comptabilit\u00e9. Ses informations sont utiles pour organiser la gestion financi\u00e8re et se conformer \u00e0 la r\u00e9glementation en vigueur. Il ne faut donc pas n\u00e9gliger son importance dans votre gestion comptable.&nbsp;<\/p>\n\n\n\n<p class=\"has-text-align-center\"><a href=\"https:\/\/ipaidthat.io\/mag\/comptabilite\/serie-la-gestion-de-la-comptabilite-comme-un-pro-2\/\" target=\"_blank\" rel=\"noreferrer noopener\"><strong>Pour g\u00e9rer votre comptabilit\u00e9 comme un pro, <\/strong><\/a><strong><a href=\"https:\/\/ipaidthat.io\/mag\/comptabilite\/serie-la-gestion-de-la-comptabilite-comme-un-pro-2\/\"><strong>consultez cet autre article<\/strong><\/a> !<\/strong><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Selon le Code de commerce, toute personne physique ou morale ayant la qualit\u00e9 de commer\u00e7ant doit enregistrer chronologiquement les op\u00e9rations li\u00e9es \u00e0 son activit\u00e9 et \u00e9tablir des comptes annuels \u00e0 la cl\u00f4ture de son exercice. En France, la tenue de la comptabilit\u00e9 est encadr\u00e9e par la loi et doit se conformer aux r\u00e8gles \u00e9nonc\u00e9es dans [&hellip;]<\/p>\n","protected":false},"author":4,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[5,4],"tags":[],"class_list":["post-11688","post","type-post","status-publish","format-standard","hentry","category-comptabilite","category-featured"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v26.6 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Plan comptable g\u00e9n\u00e9ral : d\u00e9finition, int\u00e9r\u00eat et notions cl\u00e9s<\/title>\n<meta name=\"description\" content=\"Le plan comptable g\u00e9n\u00e9ral est le document de r\u00e9f\u00e9rence pour la tenue de la comptabilit\u00e9 de votre entreprise. D\u00e9couvrez ses notions cl\u00e9s.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/app.ipaidthat.io\/mag\/featured\/plan-comptable-general-le-guide-pour-la-tenue-de-votre-comptabilite\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Plan comptable g\u00e9n\u00e9ral : d\u00e9finition, int\u00e9r\u00eat et notions cl\u00e9s\" \/>\n<meta property=\"og:description\" content=\"Le plan comptable g\u00e9n\u00e9ral est le document de r\u00e9f\u00e9rence pour la tenue de la comptabilit\u00e9 de votre entreprise. D\u00e9couvrez ses notions cl\u00e9s.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/app.ipaidthat.io\/mag\/featured\/plan-comptable-general-le-guide-pour-la-tenue-de-votre-comptabilite\/\" \/>\n<meta property=\"og:site_name\" content=\"iPaidThat Mag\" \/>\n<meta property=\"article:published_time\" content=\"2022-08-10T10:05:00+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/ipaidthat.io\/mag\/wp-content\/uploads\/2022\/03\/banniere_mag_blog_compta_8.png\" \/>\n<meta name=\"author\" content=\"S\u00e9bastien Claeys\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"S\u00e9bastien Claeys\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"11 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/app.ipaidthat.io\/mag\/featured\/plan-comptable-general-le-guide-pour-la-tenue-de-votre-comptabilite\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/app.ipaidthat.io\/mag\/featured\/plan-comptable-general-le-guide-pour-la-tenue-de-votre-comptabilite\/\"},\"author\":{\"name\":\"S\u00e9bastien Claeys\",\"@id\":\"https:\/\/app.ipaidthat.io\/mag\/#\/schema\/person\/021144662586a12df79c88913050baaa\"},\"headline\":\"Plan comptable g\u00e9n\u00e9ral : La tenue de votre comptabilit\u00e9\",\"datePublished\":\"2022-08-10T10:05:00+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/app.ipaidthat.io\/mag\/featured\/plan-comptable-general-le-guide-pour-la-tenue-de-votre-comptabilite\/\"},\"wordCount\":2344,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/app.ipaidthat.io\/mag\/#organization\"},\"image\":{\"@id\":\"https:\/\/app.ipaidthat.io\/mag\/featured\/plan-comptable-general-le-guide-pour-la-tenue-de-votre-comptabilite\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/ipaidthat.io\/mag\/wp-content\/uploads\/2022\/03\/banniere_mag_blog_compta_8.png\",\"articleSection\":[\"Comptabilit\u00e9\",\"Featured\"],\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/app.ipaidthat.io\/mag\/featured\/plan-comptable-general-le-guide-pour-la-tenue-de-votre-comptabilite\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/app.ipaidthat.io\/mag\/featured\/plan-comptable-general-le-guide-pour-la-tenue-de-votre-comptabilite\/\",\"url\":\"https:\/\/app.ipaidthat.io\/mag\/featured\/plan-comptable-general-le-guide-pour-la-tenue-de-votre-comptabilite\/\",\"name\":\"Plan comptable g\u00e9n\u00e9ral : d\u00e9finition, int\u00e9r\u00eat et notions cl\u00e9s\",\"isPartOf\":{\"@id\":\"https:\/\/app.ipaidthat.io\/mag\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/app.ipaidthat.io\/mag\/featured\/plan-comptable-general-le-guide-pour-la-tenue-de-votre-comptabilite\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/app.ipaidthat.io\/mag\/featured\/plan-comptable-general-le-guide-pour-la-tenue-de-votre-comptabilite\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/ipaidthat.io\/mag\/wp-content\/uploads\/2022\/03\/banniere_mag_blog_compta_8.png\",\"datePublished\":\"2022-08-10T10:05:00+00:00\",\"description\":\"Le plan comptable g\u00e9n\u00e9ral est le document de r\u00e9f\u00e9rence pour la tenue de la comptabilit\u00e9 de votre entreprise. D\u00e9couvrez ses notions cl\u00e9s.\",\"breadcrumb\":{\"@id\":\"https:\/\/app.ipaidthat.io\/mag\/featured\/plan-comptable-general-le-guide-pour-la-tenue-de-votre-comptabilite\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/app.ipaidthat.io\/mag\/featured\/plan-comptable-general-le-guide-pour-la-tenue-de-votre-comptabilite\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/app.ipaidthat.io\/mag\/featured\/plan-comptable-general-le-guide-pour-la-tenue-de-votre-comptabilite\/#primaryimage\",\"url\":\"https:\/\/ipaidthat.io\/mag\/wp-content\/uploads\/2022\/03\/banniere_mag_blog_compta_8.png\",\"contentUrl\":\"https:\/\/ipaidthat.io\/mag\/wp-content\/uploads\/2022\/03\/banniere_mag_blog_compta_8.png\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/app.ipaidthat.io\/mag\/featured\/plan-comptable-general-le-guide-pour-la-tenue-de-votre-comptabilite\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Le Mag\",\"item\":\"https:\/\/app.ipaidthat.io\/mag\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Plan comptable g\u00e9n\u00e9ral : La tenue de votre comptabilit\u00e9\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/app.ipaidthat.io\/mag\/#website\",\"url\":\"https:\/\/app.ipaidthat.io\/mag\/\",\"name\":\"IPaidThat Mag\",\"description\":\"Une gestion simple, automatis\u00e9e et collaborative\",\"publisher\":{\"@id\":\"https:\/\/app.ipaidthat.io\/mag\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/app.ipaidthat.io\/mag\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/app.ipaidthat.io\/mag\/#organization\",\"name\":\"IPaidThat Mag\",\"url\":\"https:\/\/app.ipaidthat.io\/mag\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/app.ipaidthat.io\/mag\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/app.ipaidthat.io\/mag\/wp-content\/uploads\/2025\/11\/logo-le-mag-blog-ipaidthat.png\",\"contentUrl\":\"https:\/\/app.ipaidthat.io\/mag\/wp-content\/uploads\/2025\/11\/logo-le-mag-blog-ipaidthat.png\",\"width\":1817,\"height\":524,\"caption\":\"IPaidThat Mag\"},\"image\":{\"@id\":\"https:\/\/app.ipaidthat.io\/mag\/#\/schema\/logo\/image\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\/\/app.ipaidthat.io\/mag\/#\/schema\/person\/021144662586a12df79c88913050baaa\",\"name\":\"S\u00e9bastien Claeys\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/app.ipaidthat.io\/mag\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/app.ipaidthat.io\/mag\/wp-content\/uploads\/2023\/02\/sebastien-clayes-ipaidthat-96x96.png\",\"contentUrl\":\"https:\/\/app.ipaidthat.io\/mag\/wp-content\/uploads\/2023\/02\/sebastien-clayes-ipaidthat-96x96.png\",\"caption\":\"S\u00e9bastien Claeys\"},\"url\":\"https:\/\/app.ipaidthat.io\/mag\/author\/sebastienipaidthat-io\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Plan comptable g\u00e9n\u00e9ral : d\u00e9finition, int\u00e9r\u00eat et notions cl\u00e9s","description":"Le plan comptable g\u00e9n\u00e9ral est le document de r\u00e9f\u00e9rence pour la tenue de la comptabilit\u00e9 de votre entreprise. D\u00e9couvrez ses notions cl\u00e9s.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/app.ipaidthat.io\/mag\/featured\/plan-comptable-general-le-guide-pour-la-tenue-de-votre-comptabilite\/","og_locale":"fr_FR","og_type":"article","og_title":"Plan comptable g\u00e9n\u00e9ral : d\u00e9finition, int\u00e9r\u00eat et notions cl\u00e9s","og_description":"Le plan comptable g\u00e9n\u00e9ral est le document de r\u00e9f\u00e9rence pour la tenue de la comptabilit\u00e9 de votre entreprise. D\u00e9couvrez ses notions cl\u00e9s.","og_url":"https:\/\/app.ipaidthat.io\/mag\/featured\/plan-comptable-general-le-guide-pour-la-tenue-de-votre-comptabilite\/","og_site_name":"iPaidThat Mag","article_published_time":"2022-08-10T10:05:00+00:00","og_image":[{"url":"https:\/\/ipaidthat.io\/mag\/wp-content\/uploads\/2022\/03\/banniere_mag_blog_compta_8.png","type":"","width":"","height":""}],"author":"S\u00e9bastien Claeys","twitter_card":"summary_large_image","twitter_misc":{"\u00c9crit par":"S\u00e9bastien Claeys","Dur\u00e9e de lecture estim\u00e9e":"11 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/app.ipaidthat.io\/mag\/featured\/plan-comptable-general-le-guide-pour-la-tenue-de-votre-comptabilite\/#article","isPartOf":{"@id":"https:\/\/app.ipaidthat.io\/mag\/featured\/plan-comptable-general-le-guide-pour-la-tenue-de-votre-comptabilite\/"},"author":{"name":"S\u00e9bastien Claeys","@id":"https:\/\/app.ipaidthat.io\/mag\/#\/schema\/person\/021144662586a12df79c88913050baaa"},"headline":"Plan comptable g\u00e9n\u00e9ral : La tenue de votre comptabilit\u00e9","datePublished":"2022-08-10T10:05:00+00:00","mainEntityOfPage":{"@id":"https:\/\/app.ipaidthat.io\/mag\/featured\/plan-comptable-general-le-guide-pour-la-tenue-de-votre-comptabilite\/"},"wordCount":2344,"commentCount":0,"publisher":{"@id":"https:\/\/app.ipaidthat.io\/mag\/#organization"},"image":{"@id":"https:\/\/app.ipaidthat.io\/mag\/featured\/plan-comptable-general-le-guide-pour-la-tenue-de-votre-comptabilite\/#primaryimage"},"thumbnailUrl":"https:\/\/ipaidthat.io\/mag\/wp-content\/uploads\/2022\/03\/banniere_mag_blog_compta_8.png","articleSection":["Comptabilit\u00e9","Featured"],"inLanguage":"fr-FR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/app.ipaidthat.io\/mag\/featured\/plan-comptable-general-le-guide-pour-la-tenue-de-votre-comptabilite\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/app.ipaidthat.io\/mag\/featured\/plan-comptable-general-le-guide-pour-la-tenue-de-votre-comptabilite\/","url":"https:\/\/app.ipaidthat.io\/mag\/featured\/plan-comptable-general-le-guide-pour-la-tenue-de-votre-comptabilite\/","name":"Plan comptable g\u00e9n\u00e9ral : d\u00e9finition, int\u00e9r\u00eat et notions cl\u00e9s","isPartOf":{"@id":"https:\/\/app.ipaidthat.io\/mag\/#website"},"primaryImageOfPage":{"@id":"https:\/\/app.ipaidthat.io\/mag\/featured\/plan-comptable-general-le-guide-pour-la-tenue-de-votre-comptabilite\/#primaryimage"},"image":{"@id":"https:\/\/app.ipaidthat.io\/mag\/featured\/plan-comptable-general-le-guide-pour-la-tenue-de-votre-comptabilite\/#primaryimage"},"thumbnailUrl":"https:\/\/ipaidthat.io\/mag\/wp-content\/uploads\/2022\/03\/banniere_mag_blog_compta_8.png","datePublished":"2022-08-10T10:05:00+00:00","description":"Le plan comptable g\u00e9n\u00e9ral est le document de r\u00e9f\u00e9rence pour la tenue de la comptabilit\u00e9 de votre entreprise. D\u00e9couvrez ses notions cl\u00e9s.","breadcrumb":{"@id":"https:\/\/app.ipaidthat.io\/mag\/featured\/plan-comptable-general-le-guide-pour-la-tenue-de-votre-comptabilite\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/app.ipaidthat.io\/mag\/featured\/plan-comptable-general-le-guide-pour-la-tenue-de-votre-comptabilite\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/app.ipaidthat.io\/mag\/featured\/plan-comptable-general-le-guide-pour-la-tenue-de-votre-comptabilite\/#primaryimage","url":"https:\/\/ipaidthat.io\/mag\/wp-content\/uploads\/2022\/03\/banniere_mag_blog_compta_8.png","contentUrl":"https:\/\/ipaidthat.io\/mag\/wp-content\/uploads\/2022\/03\/banniere_mag_blog_compta_8.png"},{"@type":"BreadcrumbList","@id":"https:\/\/app.ipaidthat.io\/mag\/featured\/plan-comptable-general-le-guide-pour-la-tenue-de-votre-comptabilite\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Le Mag","item":"https:\/\/app.ipaidthat.io\/mag\/"},{"@type":"ListItem","position":2,"name":"Plan comptable g\u00e9n\u00e9ral : La tenue de votre comptabilit\u00e9"}]},{"@type":"WebSite","@id":"https:\/\/app.ipaidthat.io\/mag\/#website","url":"https:\/\/app.ipaidthat.io\/mag\/","name":"IPaidThat Mag","description":"Une gestion simple, automatis\u00e9e et collaborative","publisher":{"@id":"https:\/\/app.ipaidthat.io\/mag\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/app.ipaidthat.io\/mag\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/app.ipaidthat.io\/mag\/#organization","name":"IPaidThat Mag","url":"https:\/\/app.ipaidthat.io\/mag\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/app.ipaidthat.io\/mag\/#\/schema\/logo\/image\/","url":"https:\/\/app.ipaidthat.io\/mag\/wp-content\/uploads\/2025\/11\/logo-le-mag-blog-ipaidthat.png","contentUrl":"https:\/\/app.ipaidthat.io\/mag\/wp-content\/uploads\/2025\/11\/logo-le-mag-blog-ipaidthat.png","width":1817,"height":524,"caption":"IPaidThat Mag"},"image":{"@id":"https:\/\/app.ipaidthat.io\/mag\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/app.ipaidthat.io\/mag\/#\/schema\/person\/021144662586a12df79c88913050baaa","name":"S\u00e9bastien Claeys","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/app.ipaidthat.io\/mag\/#\/schema\/person\/image\/","url":"https:\/\/app.ipaidthat.io\/mag\/wp-content\/uploads\/2023\/02\/sebastien-clayes-ipaidthat-96x96.png","contentUrl":"https:\/\/app.ipaidthat.io\/mag\/wp-content\/uploads\/2023\/02\/sebastien-clayes-ipaidthat-96x96.png","caption":"S\u00e9bastien Claeys"},"url":"https:\/\/app.ipaidthat.io\/mag\/author\/sebastienipaidthat-io\/"}]}},"_links":{"self":[{"href":"https:\/\/app.ipaidthat.io\/mag\/wp-json\/wp\/v2\/posts\/11688","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/app.ipaidthat.io\/mag\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/app.ipaidthat.io\/mag\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/app.ipaidthat.io\/mag\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/app.ipaidthat.io\/mag\/wp-json\/wp\/v2\/comments?post=11688"}],"version-history":[{"count":0,"href":"https:\/\/app.ipaidthat.io\/mag\/wp-json\/wp\/v2\/posts\/11688\/revisions"}],"wp:attachment":[{"href":"https:\/\/app.ipaidthat.io\/mag\/wp-json\/wp\/v2\/media?parent=11688"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/app.ipaidthat.io\/mag\/wp-json\/wp\/v2\/categories?post=11688"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/app.ipaidthat.io\/mag\/wp-json\/wp\/v2\/tags?post=11688"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}